{"id":31592,"date":"2021-12-01T11:26:05","date_gmt":"2021-12-01T10:26:05","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=31592"},"modified":"2021-12-01T11:26:05","modified_gmt":"2021-12-01T10:26:05","slug":"rohstoffabbau-und-seine-folgen","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2021\/12\/rohstoffabbau-und-seine-folgen\/","title":{"rendered":"Rohstoffabbau und seine Folgen"},"content":{"rendered":"\n<p>S\u00f6gel &#8211; Den Sch\u00fclern der Klassen 9R der Schule am Schloss wurden durch den Umweltp\u00e4dagogen Rainer Voigt von der \u201eGEOSCOPIA UMWELTBILDUNG\u201c in Bochum in Kooperation mit Kathrin Klaffke vom Klimacenter in Werlte die Folgen des Abbaus wertvoller Rohstoffe dargestellt.<\/p>\n\n\n\n<p>Anhand von Live\u2013Satellitenbildern und informativen Grafiken wurden ihnen die weltweiten Auswirkungen vor Augen gef\u00fchrt. Dabei lernten sie, wie unser konsumorientierter Lebensstil mit den immer knapper werdenden Rohstoffressourcen zusammenh\u00e4ngt.<\/p>\n\n\n\n<p>Gemeinsam mit Herrn Voigt erarbeiteten die Jugendlichen Handlungsoptionen, mit denen man aktiv im privaten und schulischen Umfeld den sozialen und \u00f6kologischen Fu\u00dfabdruck verringern kann. Am Ende waren sich alle Beteiligten einig: Das Vermeiden, Verwerten und Recyceln anstatt un\u00fcberlegtes Kaufen und achtloses Wegwerfen unserer Konsumg\u00fcter f\u00fchrt zu einer nachhaltigen Rohstoffwende und zum wertvollen Ressourcenschutz.<\/p>\n\n\n\n<p>\u201eWir sind es unserer Erde, uns selbst und besonders euch als zuk\u00fcnftige Generation schuldig, dass wir unser eigenes Handeln in Bezug auf den Abbau und die Verschwendung von immer mehr Rohstoffen schnellstm\u00f6glich \u00fcberdenken\u201c, sagte Markus Schute, der Koordinator f\u00fcr umweltbewusstes Verhalten an der Schule am Schloss. Er bedankte sich am Ende der Veranstaltung f\u00fcr die interessanten und anschaulich gestalteten Inhalte.<\/p>\n\n\n\n<p>Text\/Foto: Gisela Arling<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Rohstoffabbau-und-seine-Folgen-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Rohstoffabbau-und-seine-Folgen-1.jpg\" alt=\"\" data-id=\"31593\" data-full-url=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Rohstoffabbau-und-seine-Folgen-1.jpg\" data-link=\"https:\/\/www.forum-soegel.de\/information\/?attachment_id=31593\" class=\"wp-image-31593\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Rohstoffabbau-und-seine-Folgen-1.jpg 1024w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Rohstoffabbau-und-seine-Folgen-1-300x225.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Rohstoffabbau-und-seine-Folgen-1-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"S\u00f6gel &#8211; Den Sch\u00fclern der Klassen 9R der Schule am Schloss wurden durch den Umweltp\u00e4dagogen Rainer Voigt von der \u201eGEOSCOPIA UMWELTBILDUNG\u201c in Bochum in Kooperation mit Kathrin Klaffke vom Klimacenter in Werlte die Folgen des Abbaus wertvoller Rohstoffe dargestellt. Anhand von Live\u2013Satellitenbildern und informativen Grafiken wurden ihnen die weltweiten Auswirkungen vor Augen gef\u00fchrt. Dabei lernten [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-31592","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/31592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=31592"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/31592\/revisions"}],"predecessor-version":[{"id":31594,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/31592\/revisions\/31594"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=31592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=31592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=31592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}