{"id":31588,"date":"2021-12-01T11:24:58","date_gmt":"2021-12-01T10:24:58","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=31588"},"modified":"2021-12-01T11:24:58","modified_gmt":"2021-12-01T10:24:58","slug":"platt-workshop-mit-jochen-wiegand-in-der-grundschule-st-johannes","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2021\/12\/platt-workshop-mit-jochen-wiegand-in-der-grundschule-st-johannes\/","title":{"rendered":"Platt-Workshop mit Jochen Wiegand in der Grundschule St. Johannes"},"content":{"rendered":"\n<p>Spahnharrenst\u00e4tte &#8211; Am Freitag gab es an der Grundschule f\u00fcr die Kinder der 3. und 4. Klasse einen Workshop Platt mit Jochen Wiegand.<\/p>\n\n\n\n<p>Der Musiker, Liederforschen und Entertainer besch\u00e4ftigt sich seit langem mit der Herkunft vieler plattdeutscher Lieder und Begriffe.<\/p>\n\n\n\n<p>Die Kinder erfuhren dabei anhand des alten Liedes \u201eL\u00fctt Matten de Hoas\u201c einiges \u00fcber den Ursprung und die Herkunft von plattdeutschen W\u00f6rtern.<\/p>\n\n\n\n<p>So erkl\u00e4rte er den Kindern z.B. die Herkunft des Begriffs \u201eBangeb\u00fcx\u201c. Selbstverst\u00e4ndlich \u00fcbersetzten die Sch\u00fcler\/innen den Begriff mit \u201eAngsthase\u201c. Dass es aber eigentlich ja \u201eAngsthose\u201c hei\u00dfen muss, fanden die Kinder witzig.&nbsp; Herr Wiegend erz\u00e4hlte ihnen, dass dies mit den ersten \u201eHosen\u201c, die aus Hasenfellen gebunden wurden, zu tun hat.<\/p>\n\n\n\n<p>Im Anschluss an den Vortrag des K\u00fcnstlers gaben die Kinder einen Einblick in ihr K\u00f6nnen und stellten Lieder aus ihrem plattdeutschen Repertoire vor.<\/p>\n\n\n\n<p>Am Abend tritt Herr Wiegand im Rahmen des PlattSatt Festivals im Ludmillenhof in S\u00f6gel unter dem Titel \u201eHool dien Muul un sing mit!\u201c &#8211; Plattd\u00fctsche Leeder un bannig Vertellen \u2013 auf. Hier wird auch unsere Siegerin des Plattdeutschen Vorlesewettbewerbs Luise Steenken auftreten und ihren Lesetext noch einmal vor gro\u00dfem Publikum vortragen.<\/p>\n\n\n\n<p>Text\/Foto: Grundschule Spahnharrenst\u00e4tte<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"768\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Platt-Workshop-mit-Jochen-Wiegand-in-der-Grundschule-St.-Johannes-2.jpg\" alt=\"\" data-id=\"31589\" data-full-url=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Platt-Workshop-mit-Jochen-Wiegand-in-der-Grundschule-St.-Johannes-2.jpg\" data-link=\"https:\/\/www.forum-soegel.de\/information\/?attachment_id=31589\" class=\"wp-image-31589\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Platt-Workshop-mit-Jochen-Wiegand-in-der-Grundschule-St.-Johannes-2.jpg 576w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Platt-Workshop-mit-Jochen-Wiegand-in-der-Grundschule-St.-Johannes-2-225x300.jpg 225w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"629\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Platt-Workshop-mit-Jochen-Wiegand-in-der-Grundschule-St.-Johannes-3.jpg\" alt=\"\" data-id=\"31590\" data-full-url=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Platt-Workshop-mit-Jochen-Wiegand-in-der-Grundschule-St.-Johannes-3.jpg\" data-link=\"https:\/\/www.forum-soegel.de\/information\/?attachment_id=31590\" class=\"wp-image-31590\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Platt-Workshop-mit-Jochen-Wiegand-in-der-Grundschule-St.-Johannes-3.jpg 1024w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Platt-Workshop-mit-Jochen-Wiegand-in-der-Grundschule-St.-Johannes-3-300x184.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/12\/Platt-Workshop-mit-Jochen-Wiegand-in-der-Grundschule-St.-Johannes-3-768x472.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"Spahnharrenst\u00e4tte &#8211; Am Freitag gab es an der Grundschule f\u00fcr die Kinder der 3. und 4. Klasse einen Workshop Platt mit Jochen Wiegand. Der Musiker, Liederforschen und Entertainer besch\u00e4ftigt sich seit langem mit der Herkunft vieler plattdeutscher Lieder und Begriffe. Die Kinder erfuhren dabei anhand des alten Liedes \u201eL\u00fctt Matten de Hoas\u201c einiges \u00fcber den [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-31588","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/31588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=31588"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/31588\/revisions"}],"predecessor-version":[{"id":31591,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/31588\/revisions\/31591"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=31588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=31588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=31588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}