{"id":31076,"date":"2021-07-05T14:45:19","date_gmt":"2021-07-05T12:45:19","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=31076"},"modified":"2021-07-05T14:45:19","modified_gmt":"2021-07-05T12:45:19","slug":"samtgemeinde-soegel-erhaelt-ueber-eine-halbe-millionen-euro-fuer-bernhardschule","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2021\/07\/samtgemeinde-soegel-erhaelt-ueber-eine-halbe-millionen-euro-fuer-bernhardschule\/","title":{"rendered":"Samtgemeinde S\u00f6gel erh\u00e4lt \u00fcber eine halbe Millionen Euro f\u00fcr Bernhardschule"},"content":{"rendered":"\n<p><em>529.000 Euro f\u00fcr Neubau der Ganztagsbetreuung \u2013 Dank an MdB Connemann<\/em><\/p>\n\n\n\n<p>S\u00f6gel &#8211; Aufatmen im Rathaus S\u00f6gel: Die Samtgemeinde S\u00f6gel erh\u00e4lt f\u00fcr den Neubau des Ganztagsbereichs an der Grundschule S\u00f6gel einen Bundeszuschuss in H\u00f6he von 529.000 Euro.<\/p>\n\n\n\n<p>\u00dcber die Nachricht der Bundestagsabgeordneten Gitta Connemann (CDU) freute sich nicht nur Samtgemeindeb\u00fcrgermeister G\u00fcnter Wigbers, sondern vor allem auch Silvia Schmid als Schulleiterin der Bernhardschule. MdB Gitta Connemann begr\u00fcndete die F\u00f6rderung wie folgt: \u201eEs braucht mehr gute Betreuungsm\u00f6glichkeiten f\u00fcr Grundschulkinder &#8211; auch \u00fcber den Mittag hinaus. 3,5 Milliarden Euro investiert die Bundesregierung in den Ausbau und damit f\u00fcr bessere individuelle F\u00f6rderung von Sch\u00fclerinnen und Sch\u00fclern, bessere Teilhabechancen benachteiligter Kinder, bessere Vereinbarkeit von Familie und Beruf. Davon bekommt jetzt die Samtgemeinde S\u00f6gel f\u00fcr den Ausbau der Ganztagsbetreuung eine F\u00f6rdersumme in H\u00f6he von 529.000 Euro. Herzlichen Gl\u00fcckwunsch f\u00fcr die gute Vorbereitung!\u201c<\/p>\n\n\n\n<p>Die Bundesregierung treibe den Ausbau der Ganztagsbetreuung in Grundschulen voran. Ab dem Schuljahr 2026\/2027 soll es f\u00fcr jedes Grundschulkind nach und nach einen entsprechenden Rechtsanspruch geben. \u201eUnd bis dahin m\u00fcssen wir die daf\u00fcr notwendige Infrastruktur stehen haben!\u201c, so Connemann.<\/p>\n\n\n\n<p>Samtgemeindeb\u00fcrgermeister G\u00fcnter Wigbers sprach von einer exzellenten Zusammenarbeit zwischen seinem Rathausteam, der Schule und dem Architekturb\u00fcro. \u201eWir haben erst im Januar die F\u00f6rderrichtlinie auf dem Tisch gehabt, uns dann aber sehr schnell gemeinsam mit der Schule entschieden, einen F\u00f6rderantrag auf den Weg zu bringen. Die Herausforderung sei dabei laut Wigbers, &#8222;unglaublich enge Fristen&#8220; einhalten zu m\u00fcssen: die Ma\u00dfnahmen mussten bis zum 1. M\u00e4rz beantragt und m\u00fcssen bis Ende 2021 auch bereits komplett umgesetzt werden. Den Bauzeitenplan anzupassen, bedeutet auch f\u00fcr die Schule eine organisatorische Herausforderung; gemeinsam aber werden wir das wohl hinbekommen.\u201c<\/p>\n\n\n\n<p>Mit der Antragstellung war die Samtgemeinde S\u00f6gel ganz schnell, bescheinigte dann auch Connemann. Fachbereichsleiter Schulen Arnold Welling dazu: \u201eUns ist zugutegekommen, dass wir ohnehin mit dem geplanten Neubau und der Sanierung der Grundschule in S\u00f6gel alle erforderlichen Unterlagen und Genehmigungen parat hatten. Wir brauchten die Pl\u00e4ne nur geringf\u00fcgig entsprechend der Kriterien des F\u00f6rderprogramms modifizieren und den Antrag auf dem Weg bringen.\u201c<\/p>\n\n\n\n<p>Mit den F\u00f6rdermitteln soll insbesondere die Umfunktionierung des ehemaligen Verwaltungstraktes in einen Ganztagsbetreuungsbereich mit R\u00e4umlichkeiten f\u00fcr die Hausaufgabenbetreuung, eine neue Ausgabek\u00fcche, ein Hauswirtschaftsraum, ein B\u00fcro f\u00fcr Schulsozialarbeiter, Spiel- und Sportger\u00e4te f\u00fcr den Au\u00dfenbereich und zahlreiches Mobiliar finanziert werden.<\/p>\n\n\n\n<p>Text: Ingrid Cloppenburg<\/p>\n\n\n\n<p>Foto: Samtgemeinde S\u00f6gel<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/07\/Samtgemeinde-Soegel-erhaelt-ueber-eine-halbe-Millionen-Euro-fuer-Bernhardschule-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/07\/Samtgemeinde-Soegel-erhaelt-ueber-eine-halbe-Millionen-Euro-fuer-Bernhardschule-1-1024x768.jpg\" alt=\"\" data-id=\"31077\" data-full-url=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/07\/Samtgemeinde-Soegel-erhaelt-ueber-eine-halbe-Millionen-Euro-fuer-Bernhardschule-1-scaled.jpg\" data-link=\"https:\/\/www.forum-soegel.de\/information\/?attachment_id=31077\" class=\"wp-image-31077\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/07\/Samtgemeinde-Soegel-erhaelt-ueber-eine-halbe-Millionen-Euro-fuer-Bernhardschule-1-1024x768.jpg 1024w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/07\/Samtgemeinde-Soegel-erhaelt-ueber-eine-halbe-Millionen-Euro-fuer-Bernhardschule-1-300x225.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/07\/Samtgemeinde-Soegel-erhaelt-ueber-eine-halbe-Millionen-Euro-fuer-Bernhardschule-1-768x576.jpg 768w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/07\/Samtgemeinde-Soegel-erhaelt-ueber-eine-halbe-Millionen-Euro-fuer-Bernhardschule-1-1536x1152.jpg 1536w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2021\/07\/Samtgemeinde-Soegel-erhaelt-ueber-eine-halbe-Millionen-Euro-fuer-Bernhardschule-1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><\/ul><figcaption class=\"blocks-gallery-caption\">v.l. Schulleiterin Silvia Schmit, Bundestagsabgeordnete Gitta Connemann und Samtgemeindeb\u00fcrgermeister G\u00fcnter Wigbers freuen sich \u00fcber einen Zuschuss f\u00fcr den Ausbau der Ganztagsbetreuung in H\u00f6he von 529.000 Euro.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"529.000 Euro f\u00fcr Neubau der Ganztagsbetreuung \u2013 Dank an MdB Connemann S\u00f6gel &#8211; Aufatmen im Rathaus S\u00f6gel: Die Samtgemeinde S\u00f6gel erh\u00e4lt f\u00fcr den Neubau des Ganztagsbereichs an der Grundschule S\u00f6gel einen Bundeszuschuss in H\u00f6he von 529.000 Euro. \u00dcber die Nachricht der Bundestagsabgeordneten Gitta Connemann (CDU) freute sich nicht nur Samtgemeindeb\u00fcrgermeister G\u00fcnter Wigbers, sondern vor allem [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-31076","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/31076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=31076"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/31076\/revisions"}],"predecessor-version":[{"id":31078,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/31076\/revisions\/31078"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=31076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=31076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=31076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}