{"id":2928,"date":"2010-08-08T17:05:19","date_gmt":"2010-08-08T15:05:19","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=2928"},"modified":"2010-08-08T17:11:11","modified_gmt":"2010-08-08T15:11:11","slug":"im-singing-in-the-rain","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2010\/08\/im-singing-in-the-rain\/","title":{"rendered":"I&#8217;m Singing in the Rain"},"content":{"rendered":"<p>Am 11. Juni veranstaltete der M\u00e4nnergesangverein Harmonie sein zweites Eckensingen. In diesem Jahr wurde an einigen Ecken des S\u00fcdendes Station gemacht und den dortigen Anwohner eine gesangliche Freude gemacht.<\/p>\n<p>Entlohnt wurden die S\u00e4nger nicht nur mit reichlich Applaus, sondern die Anwohner lie\u00dfen es sich auch nicht nehmen, den S\u00e4ngern auch das eine oder andere Gl\u00e4schen einzuschenken.<\/p>\n<p>Leider war der Wettergott dieser Veranstaltung nicht sonderlich hold, so dass zwischendurch immer wieder Regenschauer niedergingen. Wie man den Fotos unschwer entnehmen kann, macht singen unter dem Regenschirm auch Spa\u00df.<\/p>\n<p>Text\/Fotos: GS<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2010\/08\/MGV1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-2929\" title=\"MGV1\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2010\/08\/MGV1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0 <a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2010\/08\/MGV2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-2930\" title=\"MGV2\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2010\/08\/MGV2-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>Weitere Fotos sind unter der Kategorie &#8222;Impressionen\/Fotogalerien&#8220; ver\u00f6ffentlicht.<\/p>\n","protected":false},"excerpt":{"rendered":"Am 11. Juni veranstaltete der M\u00e4nnergesangverein Harmonie sein zweites Eckensingen. In diesem Jahr wurde an einigen Ecken des S\u00fcdendes Station gemacht und den dortigen Anwohner eine gesangliche Freude gemacht. Entlohnt wurden die S\u00e4nger nicht nur mit reichlich Applaus, sondern die Anwohner lie\u00dfen es sich auch nicht nehmen, den S\u00e4ngern auch das eine oder andere Gl\u00e4schen [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[5],"tags":[324,408,188],"class_list":["post-2928","post","type-post","status-publish","format-standard","hentry","category-was-machen-die-vereine","tag-eckensingen","tag-mgv","tag-mgv-harmonie"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/2928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=2928"}],"version-history":[{"count":3,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/2928\/revisions"}],"predecessor-version":[{"id":2934,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/2928\/revisions\/2934"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=2928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=2928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=2928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}