{"id":27950,"date":"2019-12-01T12:24:37","date_gmt":"2019-12-01T11:24:37","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=27950"},"modified":"2019-12-01T12:25:17","modified_gmt":"2019-12-01T11:25:17","slug":"bewegende-gedenkfeier-zur-reichspogromnacht","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2019\/12\/bewegende-gedenkfeier-zur-reichspogromnacht\/","title":{"rendered":"Bewegende Gedenkfeier zur Reichspogromnacht"},"content":{"rendered":"\n<p>S\u00f6gel &#8211; Auf einer bewegenden Gedenkfeier am\nFreitagvormittag in der Aula des H\u00fcmmling Gymnasiums in S\u00f6gel, welche in diesem\nJahr Sch\u00fclerinnen und Sch\u00fcler der Schule am Schloss veranstalteten, wurde den\nj\u00fcdischen NS-Opfern anl\u00e4sslich der Reichspogromnacht vor 81 Jahren gedacht. <\/p>\n\n\n\n<p>Ein besonderer Gast der Veranstaltung war John Jacobs aus\nHampshire in England. Der67-j\u00e4hrige berichtete teilweise mit tr\u00e4nenerstickter\nStimme von dem Schicksal seiner j\u00fcdischen Vorfahren, die in S\u00f6gel lebten. <\/p>\n\n\n\n<p>Durch ein Schattenspiel schilderten die Sch\u00fclerinnen und\nSch\u00fcler die Situation des Novembers 1938. <\/p>\n\n\n\n<p>Mit einem kleinen Experiment versuchten die Jugendlichen\nden in der Aula Anwesenden&nbsp; deutlich zu\nmachen was Diskriminierung bedeutet und wie es sich anf\u00fchlt ausgegrenzt zu\nwerden. So hatten die Sch\u00fcler bereits vor Beginn der Gedenkfeier die\nSitzordnung bestimmt, indem sie Zettel mit den Worten \u201eNur mit Zahnspange\u201c oder\n\u201eNur mit Ohrringen\u201c an die Sitzreihen anbrachten. <\/p>\n\n\n\n<p>Weiterhin wurde auf die aktuelle gesellschaftliche\nEntwicklung Bezug genommen: \u201eAuf erschreckende Weise erstarkt derzeit der\nPopulismus. So was d\u00fcrfen wir nicht zulassen \u2013 nie wieder!\u201c <\/p>\n\n\n\n<p>Als Erinnerung an die Opfer z\u00fcndeten die Sch\u00fcler\ngemeinsam mit B\u00fcrgermeisterin Irmgard Welling am Ende der Gedenkfeier vier Lichter\nf\u00fcr die Familie Jacobs an. <\/p>\n\n\n\n<p>Text\/Foto: Lina Breer<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/12\/Bewegende-Gedenkfeier-zur-Reichspogromnacht.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"685\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/12\/Bewegende-Gedenkfeier-zur-Reichspogromnacht.jpg\" alt=\"\" class=\"wp-image-27951\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/12\/Bewegende-Gedenkfeier-zur-Reichspogromnacht.jpg 1024w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/12\/Bewegende-Gedenkfeier-zur-Reichspogromnacht-300x201.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/12\/Bewegende-Gedenkfeier-zur-Reichspogromnacht-768x514.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"S\u00f6gel &#8211; Auf einer bewegenden Gedenkfeier am Freitagvormittag in der Aula des H\u00fcmmling Gymnasiums in S\u00f6gel, welche in diesem Jahr Sch\u00fclerinnen und Sch\u00fcler der Schule am Schloss veranstalteten, wurde den j\u00fcdischen NS-Opfern anl\u00e4sslich der Reichspogromnacht vor 81 Jahren gedacht. Ein besonderer Gast der Veranstaltung war John Jacobs aus Hampshire in England. Der67-j\u00e4hrige berichtete teilweise mit [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-27950","post","type-post","status-publish","format-standard","hentry","category-aktuelles-aus-der-region"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=27950"}],"version-history":[{"count":2,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27950\/revisions"}],"predecessor-version":[{"id":27953,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27950\/revisions\/27953"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=27950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=27950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=27950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}