{"id":27919,"date":"2019-11-01T15:57:00","date_gmt":"2019-11-01T14:57:00","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=27919"},"modified":"2019-11-28T15:57:58","modified_gmt":"2019-11-28T14:57:58","slug":"flohmarkt-fuer-spielzeug-und-kindersachen-an-der-oberschule-soegel","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2019\/11\/flohmarkt-fuer-spielzeug-und-kindersachen-an-der-oberschule-soegel\/","title":{"rendered":"Flohmarkt f\u00fcr Spielzeug und Kindersachen an der Oberschule S\u00f6gel"},"content":{"rendered":"\n<p>S\u00f6gel\n&#8211; Ihren bereits 19. Flohmarkt f\u00fcr Spielzeug und Kindersachen veranstaltet die\nOberschule S\u00f6gel am Samstag, den 9. November 2019, in ihrer Hauptstelle an der\nSchlaunallee 12. Der Flohmarkt findet wie gewohnt in der Zeit von 14.00 bis\n16.00 Uhr statt. Familien, die auf der Suche nach preiswerter Winterbekleidung\noder einem Spielzeug f\u00fcr das bevorstehende Weihnachtsfest sind, k\u00f6nnen hier\nbestimmt f\u00fcndig werden. Wer sich hingegen einen der begehrten Verkaufsst\u00e4nde\nsichern m\u00f6chte, kann sich unter der Email info@obs-soegel.de oder der\nTelefonnummer 05952 \u2013 969 360 im Sekretariat der Schule anmelden. Die\nStandgeb\u00fchr betr\u00e4gt 8,- Euro, den Verkaufsstand stellt die Schule. In der\nCafeteria der Schule sollen wieder selbstgebackene Kuchen (auch zum Mitnehmen)\nund Getr\u00e4nke angeboten werden. Die Erl\u00f6se des Flohmarktes sind f\u00fcr Projekte der\nSchule am Schloss bestimmt. <\/p>\n\n\n\n<p>Text:\nFrau Lau, Schulleiterin<\/p>\n","protected":false},"excerpt":{"rendered":"S\u00f6gel &#8211; Ihren bereits 19. Flohmarkt f\u00fcr Spielzeug und Kindersachen veranstaltet die Oberschule S\u00f6gel am Samstag, den 9. November 2019, in ihrer Hauptstelle an der Schlaunallee 12. Der Flohmarkt findet wie gewohnt in der Zeit von 14.00 bis 16.00 Uhr statt. Familien, die auf der Suche nach preiswerter Winterbekleidung oder einem Spielzeug f\u00fcr das bevorstehende [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-27919","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=27919"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27919\/revisions"}],"predecessor-version":[{"id":27920,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27919\/revisions\/27920"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=27919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=27919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=27919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}