{"id":27688,"date":"2019-10-07T17:09:36","date_gmt":"2019-10-07T15:09:36","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=27688"},"modified":"2019-10-07T17:09:36","modified_gmt":"2019-10-07T15:09:36","slug":"erster-schultag-an-der-oberschule-soegel","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2019\/10\/erster-schultag-an-der-oberschule-soegel\/","title":{"rendered":"Erster Schultag an der Oberschule S\u00f6gel"},"content":{"rendered":"<p>S\u00f6gel &#8211; \u201eDanke f\u00fcr diesen guten Morgen, danke f\u00fcr jeden neuen Tag\u201c, so ert\u00f6nte es am ersten Schultag in der Pausenhalle der Oberschule S\u00f6gel, als Kaplan Kruse Thevarajah von der katholischen Kirche St. Jakobus, Pastoralreferentin Elena Dannenberg von der evangelischen Markusgemeinde und Pfarrer Probst Marius-Gabriel Matei von der rum\u00e4nisch-orthodoxen Kirche mit den 86 neuen F\u00fcnftkl\u00e4sslern, deren Angeh\u00f6rigen und Lehrern einen \u00f6kumenischen Gottes-dienst feierten.<\/p>\n<p>Zum Thema \u201eTalente\u201c hatten Sch\u00fclerInnen des 8. Jahrgangs mit den Lehrern Anna-Maria Cloppenburg und Jan Richter die Texte vorbereitet und passende Lieder dazu ausgesucht, die Birgit B\u00fcter vom Pastoralen Team und Lehrer J\u00fcrgen Jansen auf der Gitarre begleiteten.<\/p>\n<p>Bezugnehmend auf das Gleichnis von den anvertrauten Talenten (Matth\u00e4us 25, 14-30) wurden die Neuank\u00f6mmlinge von den Geistlichen ermuntert, ihre eigenen Talente zu entdecken und auch zu nutzen. Im Anschluss an den Gottesdienst stellte Schulleiterin Maria Lau den Neuank\u00f6mmlingen ihre KlassenlehrerInnen Anna-Maria Cloppenburg, Anke Fleer, Tobias Hanekamp und Claudia Inholte vor.<\/p>\n<p>Alle neuen Sch\u00fcler und Sch\u00fclerinnen wurden dabei namentlich aufgerufen und mit herzlichem Applaus empfangen. Danach ging es mit den Klassenlehrern in die jeweiligen Klassenr\u00e4ume. F\u00fcr die Angeh\u00f6rigen gab es derweil noch Gelegenheit, bei Kaffee und Geb\u00e4ck ins Gespr\u00e4ch zu kommen oder sich noch weitere Informationen von der Schulleitung zu holen.<\/p>\n<p>Text\/Foto: Gisela Arling<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/10\/Erster-Schultag-an-der-Oberschule-S\u00f6gel-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-27689\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/10\/Erster-Schultag-an-der-Oberschule-S\u00f6gel-2-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/10\/Erster-Schultag-an-der-Oberschule-S\u00f6gel-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-27690\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/10\/Erster-Schultag-an-der-Oberschule-S\u00f6gel-1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"S\u00f6gel &#8211; \u201eDanke f\u00fcr diesen guten Morgen, danke f\u00fcr jeden neuen Tag\u201c, so ert\u00f6nte es am ersten Schultag in der Pausenhalle der Oberschule S\u00f6gel, als Kaplan Kruse Thevarajah von der katholischen Kirche St. Jakobus, Pastoralreferentin Elena Dannenberg von der evangelischen Markusgemeinde und Pfarrer Probst Marius-Gabriel Matei von der rum\u00e4nisch-orthodoxen Kirche mit den 86 neuen F\u00fcnftkl\u00e4sslern, [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-27688","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=27688"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27688\/revisions"}],"predecessor-version":[{"id":27691,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27688\/revisions\/27691"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=27688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=27688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=27688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}