{"id":27680,"date":"2019-10-07T17:07:18","date_gmt":"2019-10-07T15:07:18","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=27680"},"modified":"2019-10-07T17:07:18","modified_gmt":"2019-10-07T15:07:18","slug":"bei-bewerbung-und-vorstellungsgespraech-ueberzeugen","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2019\/10\/bei-bewerbung-und-vorstellungsgespraech-ueberzeugen\/","title":{"rendered":"Bei Bewerbung und Vorstellungsgespr\u00e4ch \u00fcberzeugen"},"content":{"rendered":"<p><strong>Bewerbungstraining an der Oberschule S\u00f6gel<\/strong><\/p>\n<p>S\u00f6gel &#8211; F\u00fcr die Sch\u00fcler und Sch\u00fclerinnen der Klassen 9 und 10 der Oberschule S\u00f6gel stand gleich zu Beginn des neuen Schuljahres ein jeweils vierst\u00fcndiges Bewerbungstraining auf dem Stundenplan. Dazu hatte der Fachbereichsleiter f\u00fcr Arbeit und Technik, Uwe Hoormann, auch in diesem Jahr in Kooperation mit der AOK Gesundheitskasse Niedersachsen Frau Julia Janning eingeladen, die die Sch\u00fclerInnen in den drei Bl\u00f6cken \u201eBewerbungsvorbereitung\u201c, \u201eBewerbungs-mappe\u201c und \u201eVorstellungsgepr\u00e4ch\u201c belehrte. Dabei ging es um die Bearbeitung der Fragen: Was geh\u00f6rt in eine schriftliche Bewerbung? Wie muss ein Bewerbungsschreiben aussehen?<\/p>\n<p>Gemeinsam mit Frau Janning wurde eine Bewerbungsmappe mit Anschreiben, Deckblatt und Lebenslauf erstellt. Im Mittelpunkt der Aktion stand jedoch das Bewerbungsgespr\u00e4ch.<\/p>\n<p>Dabei wurde der pers\u00f6nliche und \u00fcberzeugende Auftritt trainiert. \u201eDurch diese \u00dcbung soll das Selbstwertgef\u00fchl der Sch\u00fcler und Sch\u00fclerinnen gest\u00e4rkt werden\u201c, so Janning. Abschlie\u00dfend verwies sie die Sch\u00fcler noch auf die Bedeutung der eingetragenen Fehltage bzw. unentschuldigten Fehltage auf den Zeugnissen. \u201eDas Interesse der Sch\u00fclerinnen und Sch\u00fcler an dieser spannenden Bewerbungsaktion war besonders gro\u00df und ein voller Erfolg\u201c, best\u00e4tigte Klassen-lehrer Carsten L\u00fcgering im gemeinsamen Feedback.<\/p>\n<p>Text\/Foto: Gisela Arling<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/10\/Bei-Bewerbung-und-Vorstellungsgespr\u00e4ch-\u00fcberzeugen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-27681\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/10\/Bei-Bewerbung-und-Vorstellungsgespr\u00e4ch-\u00fcberzeugen-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/10\/Bei-Bewerbung-und-Vorstellungsgespr\u00e4ch-\u00fcberzeugen-300x170.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/10\/Bei-Bewerbung-und-Vorstellungsgespr\u00e4ch-\u00fcberzeugen-768x435.jpg 768w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/10\/Bei-Bewerbung-und-Vorstellungsgespr\u00e4ch-\u00fcberzeugen.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Bewerbungstraining an der Oberschule S\u00f6gel S\u00f6gel &#8211; F\u00fcr die Sch\u00fcler und Sch\u00fclerinnen der Klassen 9 und 10 der Oberschule S\u00f6gel stand gleich zu Beginn des neuen Schuljahres ein jeweils vierst\u00fcndiges Bewerbungstraining auf dem Stundenplan. Dazu hatte der Fachbereichsleiter f\u00fcr Arbeit und Technik, Uwe Hoormann, auch in diesem Jahr in Kooperation mit der AOK Gesundheitskasse Niedersachsen [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-27680","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=27680"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27680\/revisions"}],"predecessor-version":[{"id":27682,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27680\/revisions\/27682"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=27680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=27680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=27680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}