{"id":27289,"date":"2019-08-01T14:10:09","date_gmt":"2019-08-01T12:10:09","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=27289"},"modified":"2019-09-01T14:11:37","modified_gmt":"2019-09-01T12:11:37","slug":"die-klasse-3-faehrt-zum-museumsdorf","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2019\/08\/die-klasse-3-faehrt-zum-museumsdorf\/","title":{"rendered":"Die Klasse 3 f\u00e4hrt zum Museumsdorf"},"content":{"rendered":"<p>Spahnharrenst\u00e4tte &#8211; Am Mittwoch, dem 12.06.2019, ging es f\u00fcr die Drittkl\u00e4ssler zum Museumsdorf nach Cloppenburg. Dort nahmen sie an dem Programm \u201eVom Korn zum Brot\u201c teil. Anhand von Originalger\u00e4ten erfuhren die Kinder, wie von Hand geerntet, gelagert und gedroschen wurde.<\/p>\n<p>In einer der \u00e4ltesten Bockwindm\u00fchlen Niedersachsens wurde zudem anschaulich der Mahlvorgang erkl\u00e4rt. Im Anschluss daran kneteten die Kinder unter fachkundiger Anleitung einen Brotteig. Dabei erfuhren sie jede Menge \u00fcber \u201eunser t\u00e4gliches Brot\u201c und durften schlie\u00dflich ihr eigenes, nachdem es im alten Steinofen gebacken wurde, mitnehmen.<\/p>\n<p>Auf den zweiten Programmpunkt, \u201edie Dorfschulreife\u201c, waren die Kinder schon sehr gespannt, schlie\u00dflich hatten sie im Sachunterricht schon eine Menge \u00fcber \u201eSchule fr\u00fcher\u201c geh\u00f6rt.<\/p>\n<p>Es zeigte sich deutlich, wie sich Schule im Laufe der Zeit ver\u00e4ndert hatte. Vor Jahrhunderten mussten die Sch\u00fcler-\/innen ganz still und gerade sitzen und aufstehen, wenn der Lehrer sie aufrief.<\/p>\n<p>Zudem wurde in einer \u201ekomischen\u201c Schrift (der Deutschen Kurrentschrift) geschrieben. Diese probierten und \u00fcbten auch unsere Kinder, so dass sie sich am Ende \u201eim Monat Juni durch Flei\u00df und gutes Benehmen\u201c auszeichneten und ein von der \u201eLehrerin\u201c unterschriebenes Zeugnis mit nach Hause nehmen durften.<\/p>\n<p>Insgesamt war die Klassenfahrt gelungen und die Kinder der Klasse 3 fuhren begeistert, mit dem einen oder anderen Souvenir in der Tasche, nach Spahnharrenst\u00e4tte zur\u00fcck.<\/p>\n<p>Text\/Foto: WR<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/09\/Die-Klasse-3-f\u00e4hrt-zum-Museumsdorf-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-27290\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/09\/Die-Klasse-3-f\u00e4hrt-zum-Museumsdorf-3-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/09\/Die-Klasse-3-f\u00e4hrt-zum-Museumsdorf-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-27291\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/09\/Die-Klasse-3-f\u00e4hrt-zum-Museumsdorf-1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/09\/Die-Klasse-3-f\u00e4hrt-zum-Museumsdorf-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-27292\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/09\/Die-Klasse-3-f\u00e4hrt-zum-Museumsdorf-2-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Spahnharrenst\u00e4tte &#8211; Am Mittwoch, dem 12.06.2019, ging es f\u00fcr die Drittkl\u00e4ssler zum Museumsdorf nach Cloppenburg. Dort nahmen sie an dem Programm \u201eVom Korn zum Brot\u201c teil. Anhand von Originalger\u00e4ten erfuhren die Kinder, wie von Hand geerntet, gelagert und gedroschen wurde. In einer der \u00e4ltesten Bockwindm\u00fchlen Niedersachsens wurde zudem anschaulich der Mahlvorgang erkl\u00e4rt. Im Anschluss daran [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-27289","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=27289"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27289\/revisions"}],"predecessor-version":[{"id":27293,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/27289\/revisions\/27293"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=27289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=27289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=27289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}