{"id":26921,"date":"2019-06-01T19:27:03","date_gmt":"2019-06-01T17:27:03","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=26921"},"modified":"2019-07-01T19:28:14","modified_gmt":"2019-07-01T17:28:14","slug":"werlter-schueler-im-forum-soegel","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2019\/06\/werlter-schueler-im-forum-soegel\/","title":{"rendered":"Werlter Sch\u00fcler im Forum S\u00f6gel"},"content":{"rendered":"<p>S\u00f6gel &#8211; Bereits zum zweiten Mal in diesem Jahr haben Sch\u00fcler des Gymnasiums Werlte die S\u00f6geler Geschichtswerkstatt besucht.<\/p>\n<p>Im Januar arbeitete hier eine Gruppe, bestehend aus acht Sch\u00fclerInnen und zwei Lehrerinnen, mit fachkundiger Unterst\u00fctzung der Forum-Mitarbeiter an einzelnen Aspekten, die sie als Projektidee im Rahmen des Margot-Friedl\u00e4nder-Preises 2019 bei der Schwarzkopf-Stiftung Junges Europa, Berlin eingereicht hatten. Unter dem Titel \u201eNACHGEFORSCHT \u2013 NACHGEFRAGT \u2013 NACHGEHAKT\u00a0 J\u00fcdisches Leben im Emsland \u2013 Spurensuche gegen das Vergessen\u201c hat die Projektgruppe f\u00fcr ihre Idee schon jetzt einen von drei bundesweit verteilten Anerkennungspreisen gewonnen und ist mittlerweile \u2013 nach Abschluss von Recherche, Zeitzeugeninterviews und Gespr\u00e4chen in den Gemeinden \u2013 dabei, bis zum Schuljahresende die dauerhafte Ausstellung ihrer Ergebnisse in Werlte vorzubereiten. Ein herzlicher Dank gilt besonders Herrn H. Wellenbrock und Herrn H. Wichmann, deren engagierte Beitr\u00e4ge der Gruppe immer wieder wichtige Impulse gegeben haben!<\/p>\n<p>Am 9. Mai feierte die Europaschule Gymnasium Werlte einen \u201eEuropa-Tag\u201c, an dem alle Schulklassen \u2013 \u00fcber den Vormittag verteilt \u2013 eine szenische Lesung \u00fcber das Schicksal von \u201eAnne Frank\u201c h\u00f6rten und sich in unterschiedlichen Projekten mit dem Thema \u201eEuropa\u201c besch\u00e4ftigten. Die Klasse 10b, die sich zuvor im Politikunterricht \u00fcber den Europ\u00e4ischen Geschichtsweg informiert hatte, fuhr an diesem Tag in die Geschichtswerkstatt nach S\u00f6gel, wo Herr H. Wellenbrock, der die Exkursion dankenswerter Weise von Anfang bis Ende begleitete, den Sch\u00fclern exemplarisch an der Anne-Frank-Stele die Entstehung dieses Weges erl\u00e4uterte. Mit Arbeitsauftr\u00e4gen versehen, \u201eerwanderten\u201c die Sch\u00fclergruppen dann einen Teil des Weges und zeigten in der abschlie\u00dfenden Besprechung, dass sie die Bedeutung einzelner, auf den Stelen gezeigter historischer Ereignisse\/Dokumente f\u00fcr die europ\u00e4ische Geschichte durchaus ermessen konnten.<\/p>\n<p>Text\/Foto: Birgit Schmitt<br \/>\n<a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/07\/Werlter-Sch\u00fcler-im-Forum-S\u00f6gel_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-26922\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/07\/Werlter-Sch\u00fcler-im-Forum-S\u00f6gel_2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/07\/Werlter-Sch\u00fcler-im-Forum-S\u00f6gel_2-300x225.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/07\/Werlter-Sch\u00fcler-im-Forum-S\u00f6gel_2-768x576.jpg 768w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/07\/Werlter-Sch\u00fcler-im-Forum-S\u00f6gel_2.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"S\u00f6gel &#8211; Bereits zum zweiten Mal in diesem Jahr haben Sch\u00fcler des Gymnasiums Werlte die S\u00f6geler Geschichtswerkstatt besucht. Im Januar arbeitete hier eine Gruppe, bestehend aus acht Sch\u00fclerInnen und zwei Lehrerinnen, mit fachkundiger Unterst\u00fctzung der Forum-Mitarbeiter an einzelnen Aspekten, die sie als Projektidee im Rahmen des Margot-Friedl\u00e4nder-Preises 2019 bei der Schwarzkopf-Stiftung Junges Europa, Berlin eingereicht [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-26921","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=26921"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26921\/revisions"}],"predecessor-version":[{"id":26923,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26921\/revisions\/26923"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=26921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=26921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=26921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}