{"id":26894,"date":"2019-06-01T19:15:50","date_gmt":"2019-06-01T17:15:50","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=26894"},"modified":"2019-07-01T19:17:20","modified_gmt":"2019-07-01T17:17:20","slug":"ehemalige-soegeler-realschueler-treffen-sich-nach-30-jahren-wieder","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2019\/06\/ehemalige-soegeler-realschueler-treffen-sich-nach-30-jahren-wieder\/","title":{"rendered":"Ehemalige S\u00f6geler Realsch\u00fcler treffen sich nach 30 Jahren wieder"},"content":{"rendered":"<p>S\u00f6gel &#8211; Viel zu erz\u00e4hlen hatten sich die 50 ehemaligen Sch\u00fcler und Sch\u00fclerinnen des Abschlussjahrgangs 1989 der Realschule S\u00f6gel bei einem Wiedersehenstreffen in S\u00f6gel. Gro\u00df war dabei \u00a0auch \u00a0die Freude \u00fcber die\u00a0 Teilnahme der ehemaligen Lehrer Rita Anneken, Heiner Wellenbrock und Kurt Grie\u00df, der bis zum Schuljahr 1999 noch Rektor der Realschule war. Gestartet wurde mit einem Sektempfang in dem Geb\u00e4ude der damaligen Realschule in S\u00f6gel. Beim anschlie\u00dfenden Rundgang durch die R\u00e4umlichkeiten, in denen die Ehemaligen vor 30 Jahren unterrichtet wurden, erfuhren diese, dass die Realschule S\u00f6gel durch die Umstrukturierung des Schulwesens im Schuljahr 2009\/2010 in eine Haupt-, und Realschule umgewandelt wurde, die \u00a0dann \u00a02012 wieder aufgel\u00f6st und in eine schulzweigbezogene Oberschule mit offenem Ganztagsangebot umgestaltet wurde. Die weitesten Wege hatten Antje Bogner aus Garmisch in Bayern \u00a0und Hans-J\u00f6rg Perk aus Berlin auf sich genommen, um bei dem Treffen dabei zu sein. Rainer Klima, der in Malaysia lebt und nicht dabei sein konnte, hatte schon vor zwei Jahren mit den Planungen eines Treffens aller drei\u00a0 Abschlussklassen begonnen und gemeinsam mit Marion Kosse (S\u00f6gel), Bianca Untied (Werlte), Christian Sievers (B\u00f6rger) und Birgit Pawelak (Klein Berssen) das Organisationsteam gebildet. Nach einem gemeinsamen Abendessen im Clemenswerther Hof wurden alte Fotos angeschaut, Adressen ausgetauscht und in Erinnerungen geschwelgt. Zum Schluss waren sich alle einig:\u201c Es war eine sehr interessante und gelungene Veranstaltung, die in ein paar Jahren unbedingt wiederholt werden sollte\u201c.<\/p>\n<p>Text\/Foto: Gisela Arling<\/p>\n<div id=\"attachment_26895\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/07\/Ehemalige-S\u00f6geler-Realsch\u00fcler-treffen-sich-nach-30-Jahren-wieder.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-26895\" class=\"size-medium wp-image-26895\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/07\/Ehemalige-S\u00f6geler-Realsch\u00fcler-treffen-sich-nach-30-Jahren-wieder-300x177.jpg\" alt=\"\" width=\"300\" height=\"177\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/07\/Ehemalige-S\u00f6geler-Realsch\u00fcler-treffen-sich-nach-30-Jahren-wieder-300x177.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/07\/Ehemalige-S\u00f6geler-Realsch\u00fcler-treffen-sich-nach-30-Jahren-wieder-768x452.jpg 768w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/07\/Ehemalige-S\u00f6geler-Realsch\u00fcler-treffen-sich-nach-30-Jahren-wieder.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-26895\" class=\"wp-caption-text\">Die Sch\u00fclerInnen der drei Abschlussklassen des Schuljahres 1999 mit den damaligen Lehrern Rita Anneken ( Zweite von rechts, 2. Reihe), Kurt Grie\u00df (2. Reihe: mittig) und Heiner Wellenbrock (F\u00fcnfter von links, 2. Reihe ).<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"S\u00f6gel &#8211; Viel zu erz\u00e4hlen hatten sich die 50 ehemaligen Sch\u00fcler und Sch\u00fclerinnen des Abschlussjahrgangs 1989 der Realschule S\u00f6gel bei einem Wiedersehenstreffen in S\u00f6gel. Gro\u00df war dabei \u00a0auch \u00a0die Freude \u00fcber die\u00a0 Teilnahme der ehemaligen Lehrer Rita Anneken, Heiner Wellenbrock und Kurt Grie\u00df, der bis zum Schuljahr 1999 noch Rektor der Realschule war. Gestartet wurde [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-26894","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=26894"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26894\/revisions"}],"predecessor-version":[{"id":26896,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26894\/revisions\/26896"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=26894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=26894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=26894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}