{"id":26709,"date":"2019-05-05T12:20:54","date_gmt":"2019-05-05T10:20:54","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=26709"},"modified":"2019-05-05T12:20:54","modified_gmt":"2019-05-05T10:20:54","slug":"dfb-mobil-besuch-in-der-grundschule-st-johannes-spahnharrenstaette","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2019\/05\/dfb-mobil-besuch-in-der-grundschule-st-johannes-spahnharrenstaette\/","title":{"rendered":"DFB-Mobil-Besuch in der Grundschule St. Johannes Spahnharrenst\u00e4tte"},"content":{"rendered":"<p>Spahnharrenst\u00e4tte: Am Mittwoch, dem \u00a027.03.2019 besuchte das Qualifizierungsmobil des DFB die Grundschule St. Johannes. 14 Kinder der Klasse 4 und 10\u00a0 M\u00e4dchen der Klasse 3 nahmen an der kindgerechten Trainingseinheit teil.<\/p>\n<p>Die Teamer des DFB hatten B\u00e4lle ausgepackt, Pylone aufgestellt und die Kinder in zwei Gruppen eingeteilt sowie mit Leibchen in zwei verschiedenen Farben versehen. Nach einer kurzen Aufw\u00e4rmphase ging es schon mit der Ballarbeit los. Den Abschluss bildete ein \u201eChampionsleague-Turnier\u201c, das allen Beteiligten sichtbaren Spa\u00df bereitete.<\/p>\n<p>Nebenher wurden der Lehrerin, der p\u00e4dagogischen Mitarbeiterin der Grundschule St. Johannes sowie einem Jugendtrainer des \u00f6rtlichen Fu\u00dfballvereins praktische Tipps f\u00fcr attraktive Sportstunden im Rahmen der Grunderfahrungen mit dem Ball gegeben.<\/p>\n<p>Ziel dieses kostenlosen Projektes ist es, Lehrern und Vereinstrainern Anregungen und Tipps f\u00fcr die Gestaltung ihres Trainings zu geben, damit die Kinder vielseitige Bewegungserfahrungen sammeln k\u00f6nnen und mit Freude bei der Sache sind.<\/p>\n<p>W\u00e4hrend der Trainingseinheit wurden die P\u00e4dagoginnen in einem Informationsblock \u00fcber weitere Qualifizierungsangebote informiert.<\/p>\n<p>Insgesamt war es f\u00fcr alle Beteiligten ein gelungener, lehrreicher Vormittag, an dem die Kinder viel Lust am Fu\u00dfballtraining fanden.<\/p>\n<p>Text\/Foto: Werner R\u00fcdebusch<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/05\/DFB-Mobil-Besuch-in-der-Grundschule-St.-Johannes-Spahnharrenst\u00e4tte-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-26710\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/05\/DFB-Mobil-Besuch-in-der-Grundschule-St.-Johannes-Spahnharrenst\u00e4tte-3-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/05\/DFB-Mobil-Besuch-in-der-Grundschule-St.-Johannes-Spahnharrenst\u00e4tte-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-26711\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/05\/DFB-Mobil-Besuch-in-der-Grundschule-St.-Johannes-Spahnharrenst\u00e4tte-1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/05\/DFB-Mobil-Besuch-in-der-Grundschule-St.-Johannes-Spahnharrenst\u00e4tte-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-26712\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/05\/DFB-Mobil-Besuch-in-der-Grundschule-St.-Johannes-Spahnharrenst\u00e4tte-2-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Spahnharrenst\u00e4tte: Am Mittwoch, dem \u00a027.03.2019 besuchte das Qualifizierungsmobil des DFB die Grundschule St. Johannes. 14 Kinder der Klasse 4 und 10\u00a0 M\u00e4dchen der Klasse 3 nahmen an der kindgerechten Trainingseinheit teil. Die Teamer des DFB hatten B\u00e4lle ausgepackt, Pylone aufgestellt und die Kinder in zwei Gruppen eingeteilt sowie mit Leibchen in zwei verschiedenen Farben versehen. [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-26709","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=26709"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26709\/revisions"}],"predecessor-version":[{"id":26713,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26709\/revisions\/26713"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=26709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=26709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=26709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}