{"id":26706,"date":"2019-05-05T12:19:30","date_gmt":"2019-05-05T10:19:30","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=26706"},"modified":"2019-05-05T12:19:30","modified_gmt":"2019-05-05T10:19:30","slug":"an-der-grundschule-boerger-wird-das-judentum-lebendig","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2019\/05\/an-der-grundschule-boerger-wird-das-judentum-lebendig\/","title":{"rendered":"An der Grundschule B\u00f6rger wird das Judentum lebendig"},"content":{"rendered":"<p>B\u00f6rger &#8211; Die Jungen und M\u00e4dchen der vierten Klassen der Grundschule B\u00f6rger haben im Rahmen eines Projekttages viel \u00fcber das j\u00fcdische Leben erfahren. \u201eJudentum begreifen\u201c hei\u00dft ein Projekt, das die Gesellschaft f\u00fcr christlich-j\u00fcdische Zusammenarbeit in Osnabr\u00fcck entwickelt hat. Die Projektkoordinatorin Inessa Goldmann gab ihr Wissen im Rahmen der Projekttage in B\u00f6rger weiter, um \u00fcber das Judentum aufzukl\u00e4ren und Vorurteilen vorzubeugen.<\/p>\n<p>Wie sich j\u00fcdisches Leben im Alltag ausdr\u00fcckt, erlebten die Kinder zu Beginn des Projekttages in einem Filmbeitrag. Der Film f\u00fchrte die jungen Zuschauer erst zu einem Rabbi, der die besondere Bedeutung der Thora f\u00fcr das Judentum beschrieb, dann zu einem j\u00fcdischen Ladenbesitzer, der erkl\u00e4rte, was es mit der koscheren K\u00fcche auf sich hat. An einem Freitagabend besuchte der Reporter dann eine j\u00fcdische Familie, die den Schabbat vorbereitet hat. Der Schabbat ist der Ruhetag der Juden und J\u00fcdinnen.<\/p>\n<p>Im Klassenraum hatte Frau Goldmann eine kleine Ausstellung aufgebaut. Sie pr\u00e4sentierte daraus eine reich verzierte Thorarolle aus Pergament, auf die mit der Hand die f\u00fcnf B\u00fccher Mose geschrieben standen und aus der in den j\u00fcdischen Gottesdiensten gelesen wird. \u201eWir d\u00fcrfen die Thorarolle nicht ber\u00fchren, so wichtig ist sie f\u00fcr uns\u201c, erkl\u00e4rte Frau Goldmann. Den Kindern wurde anschaulich vermittelt, dass die hebr\u00e4ische Schrift ganz andere Schriftzeichen als die lateinische hat.<\/p>\n<p>Alle Kinder zeigten sich dar\u00fcber verbl\u00fcfft, dass die Schriften von rechts nach links geschrieben sind. Dann setzte Goldmann auf anschauliche Weise die mitgebrachten j\u00fcdischen Gegenst\u00e4nde ein, um das Vorwissen der Kinder zu aktivieren und um Neues zu vermitteln. Ein Kind durfte sogar den Gebetsmantel (Tallit) und die Gebetsriemen anlegen sowie eine Kippa aufsetzen. Ein besonderer H\u00f6hepunkt war, als Inessa Goldmann das Schofarhorn und seine Bedeutung f\u00fcr das Judentum erkl\u00e4rte und die Kinder selbst versuchen durften, dem Instrument einen Ton zu entlocken.<\/p>\n<p>Sp\u00e4ter stellten die Kinder dann in einem Workshop das Pessachfest nach. In der Mitte des Tisches stand der Sederteller mit seinen sechs Vertiefungen. Die Zutaten, die traditionell auf den Vertiefungen liegen, sollen den Juden und J\u00fcdinnen den Auszug der Israeliten aus der \u00e4gyptischen Sklaverei ins Ged\u00e4chtnis rufen. \u201eWoran erinnert wohl das salzige Wasser?\u201c, fragte Frau Goldmann.<\/p>\n<p>\u201eTr\u00e4nen\u201c, traute sich schlie\u00dflich eine Viertkl\u00e4sslerin zu erwidern. \u201eJa, das erinnert uns daran, wie schlecht es uns Juden in der Sklaverei gegangen ist.\u201c \u00a0Ganz anschaulich erkl\u00e4rte sie auch die Bedeutung des Lamms, der Kartoffel, des Bitterkrauts und des Mazzens. Die Kinder wirkten betroffen. Sie stellten sich vor, wie schlimm das Leben als Sklave in \u00c4gypten gewesen sein musste. Es kam zu einer nachdenklichen Stille im Klassenraum.<\/p>\n<p>Anschlie\u00dfend durften die Kinder sich dann ein Mazzen-Sandwich mit Salat, Apfelmus und Bitterkraut belegen und essen. Zu trinken gab es Traubensaft. In einem Quiz beantworteten die Kinder Fragen zum Judentum und stellten ihr erworbenes Wissen unter Beweis.<\/p>\n<p>Am Ende des Unterrichtstages hatten die Sch\u00fcler und Sch\u00fclerinnen viel vom Judentum gesehen und gelernt. Sie haben dank des Projektes \u201eJudentum begreifen\u201c bereits in der Grundschule Eindr\u00fccke sammeln k\u00f6nnen, woran Juden und J\u00fcdinnen glauben und wie sie leben, beten und feiern\u2026<\/p>\n<p>In B\u00f6rger steht das Projekt \u201eJudentum begreifen\u201c zum wiederholten Mal auf dem Stundenplan und wird nach Aussage des Schulleiters Christian Schr\u00f6er auch in Zukunft durchgef\u00fchrt werden.<\/p>\n<p><strong>\u00a0<\/strong>Text\/Foto: Christian Schr\u00f6er<\/p>\n<div id=\"attachment_26707\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/05\/An-der-Grundschule-B\u00f6rger-wird-das-Judentum-lebendig.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-26707\" class=\"size-medium wp-image-26707\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/05\/An-der-Grundschule-B\u00f6rger-wird-das-Judentum-lebendig-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/05\/An-der-Grundschule-B\u00f6rger-wird-das-Judentum-lebendig-300x225.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/05\/An-der-Grundschule-B\u00f6rger-wird-das-Judentum-lebendig-768x577.jpg 768w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/05\/An-der-Grundschule-B\u00f6rger-wird-das-Judentum-lebendig.jpg 1023w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-26707\" class=\"wp-caption-text\">Das Team um Projektleiterin Inessa Goldmann ging auf die Fragen der vierten Klasse der Grundschule B\u00f6rger ein und informierte anschaulich mithilfe der mitgebrachten Gegenst\u00e4nde \u00fcber das Judentum. Alle Kinder versuchten dem Schofarhorn einen Ton zu entlocken.<\/p><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"B\u00f6rger &#8211; Die Jungen und M\u00e4dchen der vierten Klassen der Grundschule B\u00f6rger haben im Rahmen eines Projekttages viel \u00fcber das j\u00fcdische Leben erfahren. \u201eJudentum begreifen\u201c hei\u00dft ein Projekt, das die Gesellschaft f\u00fcr christlich-j\u00fcdische Zusammenarbeit in Osnabr\u00fcck entwickelt hat. Die Projektkoordinatorin Inessa Goldmann gab ihr Wissen im Rahmen der Projekttage in B\u00f6rger weiter, um \u00fcber das [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-26706","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=26706"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26706\/revisions"}],"predecessor-version":[{"id":26708,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26706\/revisions\/26708"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=26706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=26706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=26706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}