{"id":26511,"date":"2019-04-21T13:53:44","date_gmt":"2019-04-21T11:53:44","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=26511"},"modified":"2019-04-21T13:53:44","modified_gmt":"2019-04-21T11:53:44","slug":"low-t-ball-turnier-der-grundschulen-in-der-sg-soegel","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2019\/04\/low-t-ball-turnier-der-grundschulen-in-der-sg-soegel\/","title":{"rendered":"Low-T-Ball Turnier der Grundschulen in der SG S\u00f6gel"},"content":{"rendered":"<p>B\u00f6rger &#8211; Im Rahmen der Kooperationen mit den \u00f6rtlichen Tennisvereinen und als Projekt des Schulverbundes der Grundschulen in Tr\u00e4gerschaft der Samtgemeinde S\u00f6gel fand ein Low-T-Ball Turnier in der neuen Sporthalle in B\u00f6rger statt. Im Vorfeld hatte es in den einzelnen Schulen schon Wettk\u00e4mpfe gegeben, um die Schulsieger in den Wertungsgruppen zu ermitteln. Diese 32 M\u00e4dchen und Jungen spielten dann in 8 Gruppen um Platz, Sieg und Pokale. Die Tennisregion Dollart-Ems-Vechte und der Dachverband TNB (Tennisverband Niedersachsen- Bremen) unterst\u00fctzten dabei die Organisatoren. Ziel dieses Schultenniscups ist es, Kinder an den faszinierenden und schnellen Tennissport heranzuf\u00fchren. An diesem Vormittag zeigte sich, wie geschickt und talentiert schon Erstkl\u00e4ssler mit dem Schl\u00e4ger umgehen k\u00f6nnen. Es gab viele hart umk\u00e4mpfte Begegnungen, bei denen es aber immer sehr fair zuging. Anders als im \u201erichtigen\u201c Tennis geht es beim Low-T-Ball, wie der Name schon vermuten l\u00e4sst, darum, den Ball unter einem \u201eNetz\u201c hindurchzuspielen. Der leichte Spielball in der Gr\u00f6\u00dfe eines Gymnastikballs wird dabei mit einem richtigen Tennisschl\u00e4ger unter einem Holzbrett durchgespielt. Ein weiterer Unterschied ist die Bande, die in das Spiel einbezogen werden kann. Es werden so die Reaktionen, die Auge- Hand- Koordination, das Ballgef\u00fchl und das Stellungsspiel kindgerecht ge\u00fcbt. Am Ende der spannenden Gruppenspiele konnten die Verantwortlichen der vier Grundschulen aus Werpeloh, Spahnharrenst\u00e4tte, Klein-Ber\u00dfen und B\u00f6rger allen Teilnehmern Plaketten, Urkunden und Pokale \u00fcberreichen. Alle waren sich einig,dass auch in Zukunft dieses Samtgemeindeschultennisturnier ausgetragen werden soll.<\/p>\n<p>Text\/Foto: Grundschule B\u00f6rger<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/04\/Low-T-Ball-Turnier-der-Grundschulen-in-der-SG-S\u00f6gel-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-26512\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/04\/Low-T-Ball-Turnier-der-Grundschulen-in-der-SG-S\u00f6gel-2-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/04\/Low-T-Ball-Turnier-der-Grundschulen-in-der-SG-S\u00f6gel-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-26513\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/04\/Low-T-Ball-Turnier-der-Grundschulen-in-der-SG-S\u00f6gel-1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"B\u00f6rger &#8211; Im Rahmen der Kooperationen mit den \u00f6rtlichen Tennisvereinen und als Projekt des Schulverbundes der Grundschulen in Tr\u00e4gerschaft der Samtgemeinde S\u00f6gel fand ein Low-T-Ball Turnier in der neuen Sporthalle in B\u00f6rger statt. Im Vorfeld hatte es in den einzelnen Schulen schon Wettk\u00e4mpfe gegeben, um die Schulsieger in den Wertungsgruppen zu ermitteln. Diese 32 M\u00e4dchen [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-26511","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=26511"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26511\/revisions"}],"predecessor-version":[{"id":26514,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/26511\/revisions\/26514"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=26511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=26511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=26511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}