{"id":25863,"date":"2019-01-04T12:11:39","date_gmt":"2019-01-04T11:11:39","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=25863"},"modified":"2019-01-04T12:11:39","modified_gmt":"2019-01-04T11:11:39","slug":"imker-lesen-vor","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2019\/01\/imker-lesen-vor\/","title":{"rendered":"Imker lesen vor"},"content":{"rendered":"<p><a href=\"https:\/\/www.forum-soegel.de\/information\/2019\/01\/imker-lesen-vor\/imker-lesen-vor-1\/\" rel=\"attachment wp-att-25865\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-25865\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/01\/Imker-lesen-vor-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/01\/Imker-lesen-vor-1-300x225.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/01\/Imker-lesen-vor-1-768x576.jpg 768w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/01\/Imker-lesen-vor-1.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>B\u00f6rger &#8211; Einen sehr interessanten Vormittag erlebten die Sch\u00fclerinnen und Sch\u00fcler der Grundschule B\u00f6rger am bundesweiten Vorlesetag. Sie erhielten Besuch vom Imkerverein. Die Imkerin Luise Kr\u00f6ger und die Imker Hans Theo Jansen, Rudi Schmitz, Hermann Schmitz, sowie der ehemalige Schulleiter Hubert Westerhoff gestalteten den besonderen Vormittag spannend und lehrreich. In den einzelnen Klassen wurde aus dem Buch \u201eDie Abenteuer der Biene Maja\u201c vorgelesen. Daneben konnten die Kinder eine Ausstellung \u00fcber das Leben der Bienen besuchen, die in der Pausenhalle aufgebaut worden war. Sogar ein richtiges Bienenvolk war zu beobachten. Nat\u00fcrlich ergaben sich viele Fragen rund um das Thema \u201eBiene\u201c, die von den Experten geduldig und umfassend beantwortet wurden. Ausgehend von den spannenden Abenteuern, die Maja in dem Buch mit K\u00e4fern, W\u00fcrmern, Heuschrecken, Wespen und Hornissen erlebt, wurden die Kinder in die wunderbare und faszinierende Welt der Honigbiene und ihrer Artgenossen mitgenommen.\u00a0 Jedes Jahr wird der Vorlesetag, eine Initiative der Stiftung Lesen, von Silvia Ubbenjans organisiert. Weil das Jahresthema in diesem Jahr \u201eNatur und Umwelt\u201c ist, hatte Frau Ubbenjans die Imkergruppe B\u00f6rger eingeladen. Wie wichtig das Vorlesen f\u00fcr die ganzheitliche Entwicklung des Kindes ist, beweisen langj\u00e4hrige Studien. Vorlesen steigert die Konzentrationsf\u00e4higkeit und f\u00f6rdert die Fantasie des Kindes. Das gemeinsame Zuh\u00f6ren st\u00e4rkt die soziale Kompetenz und gibt ein Gef\u00fchl f\u00fcr den Rhythmus der Sprache, was besonders auch f\u00fcr Kinder mit Migrationshintergrund die fremde Sprache erlebbarer macht. Wenn das Ganze dann noch von einer interaktiven Erlebnisausstellung begleitet wird, sind alle Sinne aktiviert und f\u00fchren zu einem nachhaltigen Lernen. So betonte auch Schulleiter Schr\u00f6er bei seinen Dankesworten an die Initiatorin und an die Vorleser seine ganz pers\u00f6nliche Begeisterung \u00fcber dieses gelungene Projekt.<\/p>\n<p>Text\/Foto: Christian Schr\u00f6er<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/2019\/01\/imker-lesen-vor\/imker-lesen-vor-2\/\" rel=\"attachment wp-att-25864\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-25864\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/01\/Imker-lesen-vor-2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/01\/Imker-lesen-vor-2-300x225.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/01\/Imker-lesen-vor-2-768x576.jpg 768w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2019\/01\/Imker-lesen-vor-2.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"B\u00f6rger &#8211; Einen sehr interessanten Vormittag erlebten die Sch\u00fclerinnen und Sch\u00fcler der Grundschule B\u00f6rger am bundesweiten Vorlesetag. Sie erhielten Besuch vom Imkerverein. Die Imkerin Luise Kr\u00f6ger und die Imker Hans Theo Jansen, Rudi Schmitz, Hermann Schmitz, sowie der ehemalige Schulleiter Hubert Westerhoff gestalteten den besonderen Vormittag spannend und lehrreich. In den einzelnen Klassen wurde aus [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-25863","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/25863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=25863"}],"version-history":[{"count":2,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/25863\/revisions"}],"predecessor-version":[{"id":25867,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/25863\/revisions\/25867"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=25863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=25863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=25863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}