{"id":25405,"date":"2018-11-02T12:35:57","date_gmt":"2018-11-02T11:35:57","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=25405"},"modified":"2018-12-02T12:36:55","modified_gmt":"2018-12-02T11:36:55","slug":"haben-sie-es-gewusst-verkehrsregeln-einfach-erklaert","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2018\/11\/haben-sie-es-gewusst-verkehrsregeln-einfach-erklaert\/","title":{"rendered":"Haben Sie es gewusst? Verkehrsregeln einfach erkl\u00e4rt!"},"content":{"rendered":"<p>Die Stra\u00dfenverkehrsordnung gibt vor, dass alle Fahrzeuge \u2013 dazu geh\u00f6ren auch Fahrr\u00e4der \u2013 nur die Fahrbahn benutzen d\u00fcrfen. Daraus ergibt sich ein absolutes Verbot des Fahrradfahrens auf reinen Gehwegen. Ausnahmen gelten nur f\u00fcr Kinder bis zu ihrem zehnten Geburtstag. Ebenso gilt, dass der Weg von Radfahrern und Fu\u00dfg\u00e4ngern gleichzeitig benutzt werden soll, wenn dieses explizit mit einem blauen Verkehrszeichen bzw. mit einem Zusatzschild \u201eRadfahrer frei\u201c ausgeschildert ist.<\/p>\n<p>Im Ortszentrum von S\u00f6gel ist eine 30er-Zone ausgewiesen, die die Radfahrer mit den anderen Verkehrsteilnehmern gleichstellt. Vor diesem Hintergrund ist im Ortszentrum der Gemeinde S\u00f6gel auf eine zus\u00e4tzliche Beschilderung verzichtet worden, denn die Radfahrer sollen aus Gr\u00fcnden der Sicherheit gesetzeskonform die Fahrbahn nutzen.<\/p>\n<p>Ferner ist wichtig:<\/p>\n<p>Innerhalb der Tempo 30-Zone im Ortszentrum gilt die Vorfahrtsregelung \u201erechts vor links\u201c. Somit ist die Clemens-August-Stra\u00dfe KEINE vorfahrtsberechtigte Stra\u00dfe! S\u00e4mtlicher Verkehr, der aus den Stra\u00dfen \u201eAm Markt\u201c und aus der Stra\u00dfe seitlich des Amtsbrunnens von rechts heraus f\u00e4hrt, hat somit Vorfahrt! Zur Verdeutlichung wurde jetzt ein neues Stra\u00dfennamensschild \u201eAm Markt\u201c aufgestellt, damit zweifelsfrei erkennbar ist, dass es sich hier um eine Stra\u00dfe und nicht nur um eine \u201eEinfahrt\u201c handelt.<\/p>\n<p>Text: Ingrid Cloppenburg<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Die Stra\u00dfenverkehrsordnung gibt vor, dass alle Fahrzeuge \u2013 dazu geh\u00f6ren auch Fahrr\u00e4der \u2013 nur die Fahrbahn benutzen d\u00fcrfen. Daraus ergibt sich ein absolutes Verbot des Fahrradfahrens auf reinen Gehwegen. Ausnahmen gelten nur f\u00fcr Kinder bis zu ihrem zehnten Geburtstag. Ebenso gilt, dass der Weg von Radfahrern und Fu\u00dfg\u00e4ngern gleichzeitig benutzt werden soll, wenn dieses explizit [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-25405","post","type-post","status-publish","format-standard","hentry","category-gut-zu-wissen"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/25405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=25405"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/25405\/revisions"}],"predecessor-version":[{"id":25406,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/25405\/revisions\/25406"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=25405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=25405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=25405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}