{"id":25184,"date":"2018-10-07T18:03:29","date_gmt":"2018-10-07T16:03:29","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=25184"},"modified":"2018-10-07T18:03:29","modified_gmt":"2018-10-07T16:03:29","slug":"sicher-im-verkehr-aktion-gelbe-fuesse","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2018\/10\/sicher-im-verkehr-aktion-gelbe-fuesse\/","title":{"rendered":"Sicher im Verkehr \u2013 Aktion \u201eGelbe F\u00fc\u00dfe\u201c"},"content":{"rendered":"<p>Spahnharrenst\u00e4tte &#8211; Am 23.08.2018 besuchte die Polizei unsere erste Klasse, um mit ihnen gelbe F\u00fc\u00dfe am Zebrastreifen aufzumalen.<\/p>\n<p>Zun\u00e4chst gab es eine kleine Einf\u00fchrung zum Thema \u201eSicher im Verkehr\u201c und den Kindern wurde erkl\u00e4rt, was die gelben F\u00fc\u00dfe bedeuten.<\/p>\n<p>Anschlie\u00dfend gingen die Erstkl\u00e4ssler mit ihrer Klassenlehrerin Frau Ostermann und dem Polizisten zum Zebrastreifen, wo auch die Kinder einen Fu\u00df aufmalen durften.<\/p>\n<p>Au\u00dferdem wurde darauf hingewiesen, worauf man als Fu\u00dfg\u00e4nger und Radfahrer am Zebrastreifen achten muss.<\/p>\n<p>Text\/Foto: WR, SPH-V<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/2018\/10\/sicher-im-verkehr-aktion-gelbe-fuesse\/sicher-im-verkehr2\/\" rel=\"attachment wp-att-25185\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-25185\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/10\/Sicher-im-Verkehr2-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.forum-soegel.de\/information\/2018\/10\/sicher-im-verkehr-aktion-gelbe-fuesse\/sicher-im-verkehr1\/\" rel=\"attachment wp-att-25186\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-25186\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/10\/Sicher-im-Verkehr1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Spahnharrenst\u00e4tte &#8211; Am 23.08.2018 besuchte die Polizei unsere erste Klasse, um mit ihnen gelbe F\u00fc\u00dfe am Zebrastreifen aufzumalen. Zun\u00e4chst gab es eine kleine Einf\u00fchrung zum Thema \u201eSicher im Verkehr\u201c und den Kindern wurde erkl\u00e4rt, was die gelben F\u00fc\u00dfe bedeuten. Anschlie\u00dfend gingen die Erstkl\u00e4ssler mit ihrer Klassenlehrerin Frau Ostermann und dem Polizisten zum Zebrastreifen, wo auch [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-25184","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/25184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=25184"}],"version-history":[{"count":2,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/25184\/revisions"}],"predecessor-version":[{"id":25188,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/25184\/revisions\/25188"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=25184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=25184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=25184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}