{"id":23355,"date":"2018-02-04T11:52:22","date_gmt":"2018-02-04T10:52:22","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=23355"},"modified":"2018-02-04T11:52:22","modified_gmt":"2018-02-04T10:52:22","slug":"verabschiedung-in-den-ruhestand-2","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2018\/02\/verabschiedung-in-den-ruhestand-2\/","title":{"rendered":"Verabschiedung in den Ruhestand"},"content":{"rendered":"<p><strong>Erna Firus hat 20 Jahre die Gro\u00dfraumturnhalle in S\u00f6gel gereinigt<\/strong><\/p>\n<p>S\u00f6gel &#8211; Im Rahmen einer Weihnachtsfeier in der Oberschule S\u00f6gel wurde Erna Firus in den Ruhestand verabschiedet. \u00a0Erster Samtgemeinderat Hans Nowak,\u00a0 der \u00a0Fachbereichsleiter f\u00fcr Schulen, Arnold Welling, \u00a0sowie Petra Nieters vom Fachdienst 2 bedankten sich \u00a0bei Frau Firus mit einer Urkunde und einem Pr\u00e4sent f\u00fcr 20 Jahre im Dienste der Samtgemeinde S\u00f6gel. \u201eDamals \u00a0sind Sie zu einer Zeit angefangen, als noch sogenannte \u201eStrukturanpassungsma\u00dfnahmen\u201c \u00a0die Regel waren.\u00a0 Im Rahmen dieser Ma\u00dfnahme haben Sie zun\u00e4chst\u00a0 als Reinigungskraft bei der Gemeinde S\u00f6gel angefangen, um schlie\u00dflich \u00a0im Dienst der Samtgemeinde S\u00f6gel \u00a0die Gro\u00dfraumturnhalle zu reinigen. Sie haben einen gro\u00dfen Dank verdient f\u00fcr \u00fcber 20 Jahre zuverl\u00e4ssige\u00a0 und engagierte Arbeit\u201c, sagte Hans Nowak. \u00a0Mit Hausmeister Hermann Windhaus, \u00a0der im letzten Sommer leider verstarb und der\u00a0 stets \u00a0mit viel Leidenschaft die Halle pflegte,\u00a0 habe Frau Firus \u00fcber viele Jahre in einem\u00a0 sehr guten Miteinander zusammengearbeitet, so Nowak weiter. Inzwischen sei \u00a0die Turnhalle aber \u00a0in die Jahre gekommen und \u00a0nach \u00a040 Jahren \u00a0wohl\u00a0 der Bau einer neuen Gro\u00dfraumturnhalle erforderlich geworden.<\/p>\n<p>Schulleiterin Maria Lau \u00a0und Markus Schute vom Personalrat der Schule am Schloss bedankten sich bei \u00a0Erna Firus f\u00fcr die geleistete Arbeit \u00a0und \u00fcberreichten ein Pr\u00e4sent. \u201eIch lasse Frau Firus ungern gehen, denn sie war immer \u00a0\u00a0ordentlich, zuverl\u00e4ssig, p\u00fcnktlich und freundlich. Mit \u00a0ihren 67 Jahren\u00a0 hat\u00a0 sie nun den Ruhestand mehr als verdient\u201c,\u00a0 betonte Lau.\u00a0 Musikalisch umrahmt wurde die Feierlichkeit mit weihnachtlichen Liedbeitr\u00e4gen\u00a0 von Sch\u00fclerInnen der Klasse 5a unter der Leitung von J\u00fcrgen Jansen. F\u00fcr die tolle Leistung gab es von der Schulleiterin ein gro\u00dfes Lob, zumal sich unter den jungen Musikern\u00a0 auch Kinder mit Handicap befanden, die von Schulbegleiterin Maria Scheel betreut werden.<\/p>\n<p>Text\/Foto: Gisela Arling<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/02\/Verabschiedung-in-den-Ruhestand.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-23356\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/02\/Verabschiedung-in-den-Ruhestand-300x172.jpg\" alt=\"\" width=\"300\" height=\"172\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/02\/Verabschiedung-in-den-Ruhestand-300x172.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/02\/Verabschiedung-in-den-Ruhestand-768x440.jpg 768w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/02\/Verabschiedung-in-den-Ruhestand.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Erna Firus hat 20 Jahre die Gro\u00dfraumturnhalle in S\u00f6gel gereinigt S\u00f6gel &#8211; Im Rahmen einer Weihnachtsfeier in der Oberschule S\u00f6gel wurde Erna Firus in den Ruhestand verabschiedet. \u00a0Erster Samtgemeinderat Hans Nowak,\u00a0 der \u00a0Fachbereichsleiter f\u00fcr Schulen, Arnold Welling, \u00a0sowie Petra Nieters vom Fachdienst 2 bedankten sich \u00a0bei Frau Firus mit einer Urkunde und einem Pr\u00e4sent f\u00fcr [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-23355","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/23355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=23355"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/23355\/revisions"}],"predecessor-version":[{"id":23357,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/23355\/revisions\/23357"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=23355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=23355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=23355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}