{"id":21955,"date":"2017-07-19T20:41:32","date_gmt":"2017-07-19T18:41:32","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=21955"},"modified":"2017-07-19T20:41:32","modified_gmt":"2017-07-19T18:41:32","slug":"buechereifuehrerschein-der-vorschulkinder-der-kita-speelhus-in-der-buecherei-boerger","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2017\/07\/buechereifuehrerschein-der-vorschulkinder-der-kita-speelhus-in-der-buecherei-boerger\/","title":{"rendered":"B\u00fcchereif\u00fchrerschein der Vorschulkinder der Kita Speelhus in der B\u00fccherei B\u00f6rger"},"content":{"rendered":"<p>B\u00f6rger: Wie jedes Fr\u00fchjahr gehen die Vorschulkinder zur B\u00fccherei, um dort den B\u00fcchereif\u00fchrerschein zu machen. Mitglieder des B\u00fcchereiteams gestalten einen sch\u00f6nen Vormittag f\u00fcr die Kinder. Die Kinder lernen, wie die B\u00fccherei innen eingeteilt ist.\u00a0 Nach diesem Vormittag wissen sie, wo die Bilderb\u00fccher, die B\u00fccher f\u00fcr die erste Klasse, Sachb\u00fccher,\u00a0 Spiele, B\u00fccher f\u00fcr die Eltern, etc. stehen.<\/p>\n<p>Das Speelhus-Team bedankt sich herzlich beim B\u00fcchereiteam,\u00a0 das jedes Jahr ein tolles Programm f\u00fcr die Kinder vorbereitet.<\/p>\n<p>Ohne dieses ehrenamtliche Engagement k\u00f6nnten wir den Kindern so etwas nicht bieten. Danke!<\/p>\n<p>Text\/Foto: Frau Pohlgeers, Kita Speelhus, B\u00f6rger<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2017\/07\/B\u00fcchereif\u00fchrerschein.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-21956\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2017\/07\/B\u00fcchereif\u00fchrerschein-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2017\/07\/B\u00fcchereif\u00fchrerschein-300x169.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2017\/07\/B\u00fcchereif\u00fchrerschein-768x432.jpg 768w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2017\/07\/B\u00fcchereif\u00fchrerschein.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"B\u00f6rger: Wie jedes Fr\u00fchjahr gehen die Vorschulkinder zur B\u00fccherei, um dort den B\u00fcchereif\u00fchrerschein zu machen. Mitglieder des B\u00fcchereiteams gestalten einen sch\u00f6nen Vormittag f\u00fcr die Kinder. Die Kinder lernen, wie die B\u00fccherei innen eingeteilt ist.\u00a0 Nach diesem Vormittag wissen sie, wo die Bilderb\u00fccher, die B\u00fccher f\u00fcr die erste Klasse, Sachb\u00fccher,\u00a0 Spiele, B\u00fccher f\u00fcr die Eltern, etc. [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-21955","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/21955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=21955"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/21955\/revisions"}],"predecessor-version":[{"id":21957,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/21955\/revisions\/21957"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=21955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=21955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=21955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}