{"id":21952,"date":"2017-07-19T20:40:09","date_gmt":"2017-07-19T18:40:09","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=21952"},"modified":"2017-07-19T20:40:09","modified_gmt":"2017-07-19T18:40:09","slug":"200-euro-fuer-die-verhexten-bastelkids-von-der-kolpingfamilie-werpeloh","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2017\/07\/200-euro-fuer-die-verhexten-bastelkids-von-der-kolpingfamilie-werpeloh\/","title":{"rendered":"200 Euro f\u00fcr \u201eDie verhexten Bastelkids\u201c von der Kolpingfamilie Werpeloh"},"content":{"rendered":"<p>Werpeloh &#8211; Alle 14 Tage treffen sich \u201eDie verhexten Bastelkids\u201c zum Bastelnachmittag im Mehrgenerationenhaus in Werpeloh. Leiterin Gertrud Bolsmann hat die Bastelgruppe vor rund zwei Jahren ins Leben gerufen. Den Namen \u201eDie verhexten Bastelkids\u201c haben sich die Kinder selbst \u00fcberlegt. Unterst\u00fctzung erh\u00e4lt Gertrud Bolsmann seit einigen Wochen zus\u00e4tzlich von Jutta Sievers und Heike L\u00fcbbers. An den Bastelnachmittagen beteiligen sich jeweils 25 bis 30 Kinder im Alter von 5 bis 12 Jahren. In den 14-t\u00e4gigen Bastelstunden, die jeweils von 15.30 Uhr bis 17.30 Uhr gehen, basteln die Kinder unter ihrer Anleitung viele abwechslungsreiche Sachen und jahreszeitliche Dekorationen. Damit schm\u00fccken sie unter anderem den Weihnachtsbaum auf dem j\u00e4hrlichen Weihnachtsmarkt im Mehrgenerationenhaus und betreiben dort auch einen Stand, an dem sie ihre Sachen zum Verkauf anbieten. Heinz Schmitz und Willy Bowen von der Kolpingfamilie Werpeloh \u00fcberreichte den Bastelkids jetzt 200 Euro, damit sie auch weiterhin noch viele tolle Ideen gemeinsam kreativ umsetzen k\u00f6nnen.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Text\/Foto: Torsten Schmitz<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2017\/07\/Bastelkids-Werpeloh.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-21953\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2017\/07\/Bastelkids-Werpeloh-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2017\/07\/Bastelkids-Werpeloh-300x169.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2017\/07\/Bastelkids-Werpeloh-768x432.jpg 768w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2017\/07\/Bastelkids-Werpeloh.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Werpeloh &#8211; Alle 14 Tage treffen sich \u201eDie verhexten Bastelkids\u201c zum Bastelnachmittag im Mehrgenerationenhaus in Werpeloh. Leiterin Gertrud Bolsmann hat die Bastelgruppe vor rund zwei Jahren ins Leben gerufen. Den Namen \u201eDie verhexten Bastelkids\u201c haben sich die Kinder selbst \u00fcberlegt. Unterst\u00fctzung erh\u00e4lt Gertrud Bolsmann seit einigen Wochen zus\u00e4tzlich von Jutta Sievers und Heike L\u00fcbbers. An [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-21952","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/21952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=21952"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/21952\/revisions"}],"predecessor-version":[{"id":21954,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/21952\/revisions\/21954"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=21952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=21952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=21952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}