{"id":20651,"date":"2017-01-01T00:01:07","date_gmt":"2016-12-31T23:01:07","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=20651"},"modified":"2016-12-30T21:03:18","modified_gmt":"2016-12-30T20:03:18","slug":"gemeinderat-stavern-hat-sich-konstituiert","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2017\/01\/gemeinderat-stavern-hat-sich-konstituiert\/","title":{"rendered":"Gemeinderat Stavern hat sich konstituiert"},"content":{"rendered":"<p>Stavern &#8211; Helmut Rawe (CDU) bleibt weiterhin B\u00fcrgermeister der Gemeinde Stavern. Als Stellvertreterin steht ihm k\u00fcnftig Anke Schuckenbrock zur Seite.<\/p>\n<p>Angespannte Stimmung machte sich am vergangenen Freitag bei der konstituierenden Sitzung des Rates der Gemeinde Stavern breit. Die erforderliche \u00a0Mehrheit von 2\/3 des Rates f\u00fcr den Verzicht eines Verwaltungsausschusses konnte nicht erreicht werden, da die vier UWG- Mitglieder des Rates dagegen stimmten. Aus diesem Grunde wurde ein Verwaltungsausschuss gebildet, dem Helmut Rawe, Anke Schuckenbrock (CDU) und Gerhard Rode (UWG) angeh\u00f6ren. F\u00fcr die Wahl des B\u00fcrgermeisters schlug die CDU\u2013Fraktion Helmut Rawe vor, die UWG-Fraktion stellte keinen Gegenkandidaten auf. Rawe wurde mit sieben von elf Stimmen gew\u00e4hlt.<\/p>\n<p>Rawe zeigte sich erfreut \u00fcber das ihm entgegengebrachte Vertrauen und stellte daraufhin die Schwerpunkte f\u00fcr die weitere Ratsarbeit der n\u00e4chsten Jahre vor. \u201eDer Breitbandausbau hat einen besonders hohen Stellenwert\u201c, gab Rawe bekannt. Stavern solle mit Glasfaser ausgestattet werden. Ein weiterer Schwerpunkt werde die L\u00fcckenbebauung sein. Hierf\u00fcr sei die Samtgemeinde bereits beauftragt, m\u00f6gliche Fl\u00e4chen f\u00fcr neue Baugebiete zu pr\u00fcfen. \u201eDie Nahversorgung unserer B\u00fcrger liegt uns allen besonders am Herzen, daher arbeiten wir an einem Konzept, um die Versorgung mit Lebensmitteln zu gew\u00e4hrleisten\u201c, berichtete Rawe. Gl\u00fcckw\u00fcnsche richtete der Erste Samtgemeinderat, Hans Nowak, im Namen der Samtgemeinde aus und bot die Unterst\u00fctzung bei den verschiedenen Vorhaben an.<\/p>\n<p>Zu weiteren Kontroversen f\u00fchrte die Wahl der stellvertretenden B\u00fcrgermeister. CDU-Fraktionsvorsitzender Michael Kleefeld beantragte, nur einen Stellvertreter zu w\u00e4hlen. UWG-Vorsitzender Rode wies darauf hin, dass laut Tagesordnung mehrere Stellvertreter gew\u00e4hlt werden sollten. Erster Samtgemeinderat Nowak entgegnete, dass gem\u00e4\u00df dem Nieders\u00e4chsischen Kommunalverfassungsgesetz bis zu drei ehrenamtliche Stellvertreterinnen oder Stellvertreter des B\u00fcrgermeisters gew\u00e4hlt werden d\u00fcrfen. Vorgeschrieben seien mehrere Stellvertreter daher nicht, da dies keine \u201eMuss-Vorschrift\u201c sei. Vorgeschlagen wurden schlie\u00dflich Anke Schuckenbrock\u00a0 und Gerhard Rode f\u00fcr die Wahl des stellvertretenden B\u00fcrgermeisters. Schuckenbrock gewann die Wahl mit sieben Stimmen f\u00fcr sich. \u201eIch bedauere es sehr, eine Ratsperiode so zu beginnen\u201c, bemerkte Rode entt\u00e4uscht und beantragte im Namen der UWG die Bildung von Aussch\u00fcssen. Seiner Ansicht nach k\u00e4men die Aussch\u00fcsse \u201eJugend- und Sportausschuss\u201c, \u201eDorfentwicklungsausschuss\u201c und \u201eAusschuss f\u00fcr Wege- und Stra\u00dfenbau\u201c infrage. Hier\u00fcber wird der Gemeinderat in seiner n\u00e4chsten Sitzung beschlie\u00dfen.<\/p>\n<p>Text\/Foto: Samtgemeinde S\u00f6gel<\/p>\n<div id=\"attachment_20652\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/12\/Konstituierende-Sitzungen-in-der-Gemeinde-Gemeinderat-Stavern-hat-sich-konstituiert-4351.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20652\" class=\"size-medium wp-image-20652\" title=\"Konstituierende Sitzungen in der Gemeinde - Gemeinderat Stavern hat sich konstituiert 435\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/12\/Konstituierende-Sitzungen-in-der-Gemeinde-Gemeinderat-Stavern-hat-sich-konstituiert-4351-300x171.jpg\" alt=\"\" width=\"300\" height=\"171\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/12\/Konstituierende-Sitzungen-in-der-Gemeinde-Gemeinderat-Stavern-hat-sich-konstituiert-4351-300x171.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/12\/Konstituierende-Sitzungen-in-der-Gemeinde-Gemeinderat-Stavern-hat-sich-konstituiert-4351.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-20652\" class=\"wp-caption-text\">Der neue Gemeinderat Stavern mit dem Ersten Samtgemeinderat Hans Nowak und der Verwaltungsvertreterin Christel T\u00f6bben.<\/p><\/div>\n<div id=\"attachment_20653\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/12\/Konstituierende-Sitzungen-in-der-Gemeinde-Gemeinderat-Stavern-hat-sich-konstituiert-4381.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20653\" class=\"size-medium wp-image-20653\" title=\"Konstituierende Sitzungen in der Gemeinde - Gemeinderat Stavern hat sich konstituiert 438\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/12\/Konstituierende-Sitzungen-in-der-Gemeinde-Gemeinderat-Stavern-hat-sich-konstituiert-4381-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/12\/Konstituierende-Sitzungen-in-der-Gemeinde-Gemeinderat-Stavern-hat-sich-konstituiert-4381-300x225.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/12\/Konstituierende-Sitzungen-in-der-Gemeinde-Gemeinderat-Stavern-hat-sich-konstituiert-4381.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-20653\" class=\"wp-caption-text\">: Verwaltungsvertreterin Christel T\u00f6bben (v.l.), B\u00fcrgermeister Helmut Rawe, und Stellvertreterin Anke Schuckenbrock wurden vom Ersten Samtgemeinderat Hans Nowak zu ihren \u00c4mtern begl\u00fcckw\u00fcnscht.<\/p><\/div>\n<div id=\"attachment_20654\" style=\"width: 305px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/12\/Konstituierende-Sitzungen-in-der-Gemeinde-Gemeinderat-Stavern-hat-sich-konstituiert-4421.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20654\" class=\"size-medium wp-image-20654\" title=\"Konstituierende Sitzungen in der Gemeinde - Gemeinderat Stavern hat sich konstituiert 442\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/12\/Konstituierende-Sitzungen-in-der-Gemeinde-Gemeinderat-Stavern-hat-sich-konstituiert-4421-295x300.jpg\" alt=\"\" width=\"295\" height=\"300\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/12\/Konstituierende-Sitzungen-in-der-Gemeinde-Gemeinderat-Stavern-hat-sich-konstituiert-4421-295x300.jpg 295w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/12\/Konstituierende-Sitzungen-in-der-Gemeinde-Gemeinderat-Stavern-hat-sich-konstituiert-4421.jpg 756w\" sizes=\"auto, (max-width: 295px) 100vw, 295px\" \/><\/a><p id=\"caption-attachment-20654\" class=\"wp-caption-text\">Der wiedergew\u00e4hlte B\u00fcrgermeister der Gemeinde Stavern mit seiner neuen Stellvertreterin Anke Schuckenbrock.<\/p><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Stavern &#8211; Helmut Rawe (CDU) bleibt weiterhin B\u00fcrgermeister der Gemeinde Stavern. Als Stellvertreterin steht ihm k\u00fcnftig Anke Schuckenbrock zur Seite. Angespannte Stimmung machte sich am vergangenen Freitag bei der konstituierenden Sitzung des Rates der Gemeinde Stavern breit. Die erforderliche \u00a0Mehrheit von 2\/3 des Rates f\u00fcr den Verzicht eines Verwaltungsausschusses konnte nicht erreicht werden, da die [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-20651","post","type-post","status-publish","format-standard","hentry","category-aktuelles-aus-der-region"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/20651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=20651"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/20651\/revisions"}],"predecessor-version":[{"id":20655,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/20651\/revisions\/20655"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=20651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=20651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=20651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}