{"id":19495,"date":"2016-08-01T20:14:42","date_gmt":"2016-08-01T18:14:42","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=19495"},"modified":"2016-08-01T20:15:13","modified_gmt":"2016-08-01T18:15:13","slug":"oberschule-sogel-verabschiedet-drei-langjahrige-lehrer","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2016\/08\/oberschule-sogel-verabschiedet-drei-langjahrige-lehrer\/","title":{"rendered":"Oberschule S\u00f6gel verabschiedet drei langj\u00e4hrige Lehrer"},"content":{"rendered":"<p align=\"left\">S\u00f6gel &#8211; Im Rahmen einer Feierstunde sind drei Lehrer an der Schule am Schloss\u00a0 nach insgesamt 120 Dienstjahren \u00a0in den Ruhestand verabschiedet worden, Angela Eilermann, Michael Peters und Christa Rapin. Schulleiterin Maria Lau \u00fcberreichte ihnen die Dank- und Gl\u00fcckwunschurkunden der Landesschulbeh\u00f6rde mit den besten W\u00fcnschen f\u00fcr die Zukunft. Angela Eilermann war mit der Aufl\u00f6sung der Orientierungsstufe im Jahr 2004 an die Realschule S\u00f6gel gekommen, die im Schuljahr 2009\/2010 zu einer\u00a0 Haupt- und Realschule reformiert wurde und seit 2012 Oberschule ist. Sie hat die F\u00e4cher Deutsch, Religion und\u00a0 Kunst unterrichtet sowie unz\u00e4hlige Autorenlesungen und Vorlesewettbewerbe organisiert und \u00a0soziale Projekte, wie zuletzt das \u00b4Uganda \u2013Projekt\u00b4,\u00a0 initiiert. \u201eAu\u00dferdem hat sie in ihrer 39j\u00e4hrigen Lehrerlaufbahn den Fachbereich Religion mit sehr viel Herzblut geleitet\u201c, betonte Lau in ihrer Laudatio. Michael Peters ist mit Auslaufen der Hauptschule 2009 \u00a0zun\u00e4chst von der Bernhard- Schule S\u00f6gel an die Haupt- und Realschule gekommen und hat bis zu seiner Pensionierung an der jetzigen Oberschule Deutsch, Musik, Geschichte und Politik unterrichtet. \u201eIn seiner 42-j\u00e4hrigen Lehrerlaufbahn hat er unz\u00e4hligen Kindern auch das Gitarrespielen beigebracht und sich f\u00fcr die Schulband engagagiert\u201c, betonte Maria Lau. Christa Rapin ist ebenfalls mit Aufl\u00f6sung der Orientierungsstufe an die Realschule gekommen \u00a0und hat nach deren Aufl\u00f6sung weiterhin die F\u00e4cher Deutsch, Geschichte und\u00a0 Erdkunde an der fusionierten \u00a0Haupt- und Realschule unterrichtet. Rapin ist ebenfalls 39 Jahre im Schuldienst t\u00e4tig gewesen und \u201e hat sich in den letzten Jahren an der Oberschule S\u00f6gel als Klassenlehrerin der Abschlussklassen des Hauptschuljahrgangs verdient gemacht,\u201c sagte Lau und beendete ihre Laudatien mit den Worten: \u201eGemeinsam habt ihr in 120 Dienstjahren viele Generationen von Sch\u00fclern geformt, gebildet und erzogen und euch vielf\u00e4ltig in die Arbeit der Schule eingebracht.\u201c Der Schulpersonalrat mit Janina Brake, Markus Schute und Mechthild Ahaus-Borchers gratulierte den frisch gebackenen Pension\u00e4ren und \u00fcberreichte ihnen vom Kollegium selbst gestaltete Erinnerungsalben. Mit\u00a0 musikalischen Beitr\u00e4gen bedankte und verabschiedete sich das Kollegium beim scheidenden Lehrer-Trio. Ehemalige Sch\u00fcler der Schulband \u00fcberraschten noch \u00a0mit einer flotten Musikeinlage.<\/p>\n<p align=\"left\">Text und Foto: Gisela Arling<\/p>\n<div id=\"attachment_19496\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/08\/Oberschule-S\u00f6gel-verabschiedet-drei-langj\u00e4hrige-Lehrer1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19496\" class=\"size-medium wp-image-19496\" title=\"Oberschule S\u00f6gel verabschiedet drei langj\u00e4hrige Lehrer1\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/08\/Oberschule-S\u00f6gel-verabschiedet-drei-langj\u00e4hrige-Lehrer1-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/08\/Oberschule-S\u00f6gel-verabschiedet-drei-langj\u00e4hrige-Lehrer1-300x199.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/08\/Oberschule-S\u00f6gel-verabschiedet-drei-langj\u00e4hrige-Lehrer1.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-19496\" class=\"wp-caption-text\">Das Foto zeigt die frisch gebackenen Pension\u00e4re vorne von links: Angela Eilermann, Christa Rapin und Michael Peters mit den Personalratsmitgliedern \u2013 hinten von links : Janina Brake, Markus Schute und Mechthild Ahaus-Borchers und rechts Schulleiterin Maria Lau<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"S\u00f6gel &#8211; Im Rahmen einer Feierstunde sind drei Lehrer an der Schule am Schloss\u00a0 nach insgesamt 120 Dienstjahren \u00a0in den Ruhestand verabschiedet worden, Angela Eilermann, Michael Peters und Christa Rapin. Schulleiterin Maria Lau \u00fcberreichte ihnen die Dank- und Gl\u00fcckwunschurkunden der Landesschulbeh\u00f6rde mit den besten W\u00fcnschen f\u00fcr die Zukunft. Angela Eilermann war mit der Aufl\u00f6sung der [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-19495","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=19495"}],"version-history":[{"count":2,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19495\/revisions"}],"predecessor-version":[{"id":19499,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19495\/revisions\/19499"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=19495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=19495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=19495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}