{"id":19492,"date":"2016-08-01T20:13:22","date_gmt":"2016-08-01T18:13:22","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=19492"},"modified":"2016-08-01T20:13:22","modified_gmt":"2016-08-01T18:13:22","slug":"dankeschon-fur-ehrenamtliche-schulerlotsen","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2016\/08\/dankeschon-fur-ehrenamtliche-schulerlotsen\/","title":{"rendered":"Dankesch\u00f6n f\u00fcr ehrenamtliche Sch\u00fclerlotsen"},"content":{"rendered":"<p>B\u00f6rger\/Werlte \u2013 Seit einigen Monaten leisten die Neuntkl\u00e4ssler der Freien Realschule H\u00fcmmling gemeinsam mit vielen Erwachsenen ehrenamtlich den Sch\u00fclerlotsendienst f\u00fcr die Grundsch\u00fcler der Grundschule B\u00f6rger. F\u00fcr diesen Dienst werden aktuell besonders viele HelferInnen ben\u00f6tigt, da die Grundschule seit mehreren Monaten das Geb\u00e4ude der ehemaligen Hauptschule an der verkehrsintensiven Hauptkreuzung in B\u00f6rgers Dorfmitte bewohnt. Zum Dank f\u00fcr ihren unverzichtbaren Einsatz wurden die Sch\u00fclerInnen vom F\u00f6rderverein \u201eJuKi\u201c und der Gemeinde B\u00f6rger in die Kletterhalle Werlte eingeladen, wo sie einen sportlichen und interessanten Nachmittag erlebten \u2013 beim Erklimmen der Kletterwand, beim Erzwingen des Kletterbaumes, beim Kistenstapeln und vielem mehr. Die Grundschule, der F\u00f6rderverein und die Gemeinde freuen sich, wenn sie sich auch im neuen Schuljahr auf die Unterst\u00fctzung der Sch\u00fclerInnen verlassen k\u00f6nnen. Herzlichen Dank! Wer selbst Interesse hat, beim Sch\u00fclerlotsendienst mitzumachen, kann sich gern an den F\u00f6rderverein, die Gemeinde oder an die Grundschule wenden.<\/p>\n<p>Text\/Foto: Ansgar Kossen<\/p>\n<div id=\"attachment_19493\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/08\/Dankesch\u00f6n-f\u00fcr-ehrenamtliche-Sch\u00fclerlotsen.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19493\" class=\"size-medium wp-image-19493\" title=\"Dankesch\u00f6n f\u00fcr ehrenamtliche Sch\u00fclerlotsen\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/08\/Dankesch\u00f6n-f\u00fcr-ehrenamtliche-Sch\u00fclerlotsen-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/08\/Dankesch\u00f6n-f\u00fcr-ehrenamtliche-Sch\u00fclerlotsen-300x200.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/08\/Dankesch\u00f6n-f\u00fcr-ehrenamtliche-Sch\u00fclerlotsen.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-19493\" class=\"wp-caption-text\">Die Sch\u00fclerlotsen und ihre Begleiter hatten viel Freude an den Angeboten der Abenteuer Zeit in Werlte.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"B\u00f6rger\/Werlte \u2013 Seit einigen Monaten leisten die Neuntkl\u00e4ssler der Freien Realschule H\u00fcmmling gemeinsam mit vielen Erwachsenen ehrenamtlich den Sch\u00fclerlotsendienst f\u00fcr die Grundsch\u00fcler der Grundschule B\u00f6rger. F\u00fcr diesen Dienst werden aktuell besonders viele HelferInnen ben\u00f6tigt, da die Grundschule seit mehreren Monaten das Geb\u00e4ude der ehemaligen Hauptschule an der verkehrsintensiven Hauptkreuzung in B\u00f6rgers Dorfmitte bewohnt. Zum Dank [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-19492","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=19492"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19492\/revisions"}],"predecessor-version":[{"id":19494,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19492\/revisions\/19494"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=19492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=19492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=19492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}