{"id":19262,"date":"2016-07-04T20:10:44","date_gmt":"2016-07-04T18:10:44","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=19262"},"modified":"2016-07-04T20:10:44","modified_gmt":"2016-07-04T18:10:44","slug":"gedenken-an-judische-ns-opfer-3","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2016\/07\/gedenken-an-judische-ns-opfer-3\/","title":{"rendered":"Gedenken an j\u00fcdische NS-Opfer"},"content":{"rendered":"<p><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/07\/Gedenken-an-j\u00fcdische-NS-Opfer.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-19263\" title=\"Gedenken an j\u00fcdische NS-Opfer\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/07\/Gedenken-an-j\u00fcdische-NS-Opfer-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/07\/Gedenken-an-j\u00fcdische-NS-Opfer-300x199.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/07\/Gedenken-an-j\u00fcdische-NS-Opfer.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>S\u00f6gel \u2013 Im Gedenken an die w\u00e4hrend der Zeit des Nationalsozialismus verfolgten und ermordeten Juden aus S\u00f6gel sind nun erneut in S\u00f6gel Stolpersteine verlegt worden. Begleitet wurde das Projekt von Sch\u00fclern des achten Jahrgangs der Schule am Schloss. Zahlreiche\u00a0 Vertreter der Gemeinde, der Kirchen, der Schulen, der Partnergemeinde aus Norg, der Vereine und\u00a0 B\u00fcrgerinnen und B\u00fcrger nahmen an der Veranstaltung teil.<\/p>\n<p>Der neue Verlegungsort liegt\u00a0 Am Markt\u00a0 14, an dem \u00a0vier Steine f\u00fcr die Familie Jacobs gesetzt wurden. B\u00fcrgermeisterin Welling erinnerte an die Bewohner des Hauses Am Markt 14. Drei der vier Mitglieder der Familie Jacobs (Hedwig, Artur und Georg) wurden 1942 von den Nazis nach Theresienstadt deportiert und 1943 in Auschwitz ermordet. Johanna Jacobs verstarb im Juli 1941. Jedes Familienmitglied hat nun einen eigenen Stolperstein. Die Namen stehen auf den bronzefarbenen Steinen, die seit 2011 in der Gemeinde S\u00f6gel verlegt werden. \u00a0Der Marsch dorthin fand in v\u00f6lliger Stille statt. \u201eSo kann jeder mit seinen eigenen Gedanken zum Thema alleine sein\u201c, sagte Welling. Vor Ort setzte ein Mitarbeiter der Gemeinde die Steine ein. Einige Sch\u00fcler legten Blumen um die Gedenktafel.<\/p>\n<p>Die Schule am Schloss organisiert die Gedenkaktion im Wechsel mit dem H\u00fcmmling-Gymnasium. Das Konzept der Stolpersteine wurde von dem K\u00fcnstler Gunter Demnig entwickelt, um an das Schicksal der Menschen zu erinnern, die im Nationalsozialismus verfolgt, vertrieben oder ermordet wurden. Die Steine werden in St\u00e4dten in ganz Europa verlegt.<\/p>\n<p>Welling hatte davon berichtet, wie sie selbst mit der Geschichte und dem Genozid der Juden umgeht. \u201eS\u00f6gel sei mit 70 j\u00fcdischen Todesopfern in Relation zur Population einer der am meisten von den Massenmorden betroffenen Orte\u201c, betonte sie. Diese Geschichte versuche die Gemeinde aufzuarbeiten: Etwa der H\u00e4lfte aller get\u00f6teten Juden aus S\u00f6gel werde bisher durch Stolpersteine gedacht. Die beteiligten Sch\u00fcler sind Teilnehmer eines Wahlpflichtkurses und haben sich im vergangenen Schuljahr mit dem Thema Nationalsozialismus in der Region besch\u00e4ftigt. Sie verstehen die Stolpersteine als Denkansto\u00df, um sich mit der deutschen Geschichte auseinanderzusetzen.<\/p>\n<p>Text\/Foto: Markus K\u00fcnnen<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"S\u00f6gel \u2013 Im Gedenken an die w\u00e4hrend der Zeit des Nationalsozialismus verfolgten und ermordeten Juden aus S\u00f6gel sind nun erneut in S\u00f6gel Stolpersteine verlegt worden. Begleitet wurde das Projekt von Sch\u00fclern des achten Jahrgangs der Schule am Schloss. Zahlreiche\u00a0 Vertreter der Gemeinde, der Kirchen, der Schulen, der Partnergemeinde aus Norg, der Vereine und\u00a0 B\u00fcrgerinnen und [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-19262","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=19262"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19262\/revisions"}],"predecessor-version":[{"id":19264,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19262\/revisions\/19264"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=19262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=19262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=19262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}