{"id":19259,"date":"2016-07-04T20:09:26","date_gmt":"2016-07-04T18:09:26","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=19259"},"modified":"2016-07-04T20:09:26","modified_gmt":"2016-07-04T18:09:26","slug":"france-mobil-macht-halt-in-sogel-an-der-oberschule","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2016\/07\/france-mobil-macht-halt-in-sogel-an-der-oberschule\/","title":{"rendered":"France-Mobil macht Halt in S\u00f6gel an der Oberschule"},"content":{"rendered":"<p>S\u00f6gel &#8211; Auch in diesem Schuljahr hat das FranceMobil wieder die Schule am Schloss besucht. Seit Anfang September f\u00e4hrt der franz\u00f6sische Lektor Guilhem Arnould\u00a0 durch Bremen und Niedersachsen, um die Sch\u00fcler spielerisch im Auftrag des Institut Francais f\u00fcr die franz\u00f6sische Sprache, Frankreich und die deutsch-franz\u00f6sische Zusammenarbeit zu begeistern. Am 13.6.2016 war er an der Schule am Schloss in S\u00f6gel, um dort die Franz\u00f6sischsch\u00fclerInnen der Klassen 5-7\u00a0 zu besuchen. Ab der 6. Klasse k\u00f6nnen die Sch\u00fcler und Sch\u00fclerinnen an der Oberschule Franz\u00f6sisch als zweite Fremdsprache w\u00e4hlen. Dass die F\u00fcnftkl\u00e4ssler schon jetzt mehr als nur baguette und croissant verstehen, mag einige Sch\u00fcler\u00a0 erstaunt haben. Aber mit Hilfe von Gestik und Mimik, Bildern, Musik und Bewegungsspielen verstand Arnould es, sie 45 Minuten nur in Franz\u00f6sisch zu unterhalten.<\/p>\n<p>Das Programm FranceMobil erfreut sich seit fast 15 Jahren einer gro\u00dfen Nachfrage. \u00dcber 800.000 Sch\u00fcler in 10.000 Schulen wurden bundesweit in den letzten Jahren erreicht. Das Programm wurde 2002 von der Robert Bosch Stiftung und der Franz\u00f6sischen Botschaft in Deutschland ins Leben gerufen. Die Renault Deutschland AG stellt die Fahrzeuge zur Verf\u00fcgung, mit denen die Lektoren Kinderg\u00e4rten, Grund-, Real- und Berufsschulen sowie Oberschulen und Gymnasien in ganz Deutschland ansteuern.<\/p>\n<p>Text \/ Foto: Reinhild Gallus<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/07\/FranceMobil.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-19260\" title=\"FranceMobil\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/07\/FranceMobil-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/07\/FranceMobil-300x225.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/07\/FranceMobil.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"S\u00f6gel &#8211; Auch in diesem Schuljahr hat das FranceMobil wieder die Schule am Schloss besucht. Seit Anfang September f\u00e4hrt der franz\u00f6sische Lektor Guilhem Arnould\u00a0 durch Bremen und Niedersachsen, um die Sch\u00fcler spielerisch im Auftrag des Institut Francais f\u00fcr die franz\u00f6sische Sprache, Frankreich und die deutsch-franz\u00f6sische Zusammenarbeit zu begeistern. Am 13.6.2016 war er an der Schule [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-19259","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=19259"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19259\/revisions"}],"predecessor-version":[{"id":19261,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19259\/revisions\/19261"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=19259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=19259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=19259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}