{"id":19255,"date":"2016-07-04T20:08:18","date_gmt":"2016-07-04T18:08:18","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=19255"},"modified":"2016-07-04T20:08:18","modified_gmt":"2016-07-04T18:08:18","slug":"%e2%80%9efaires-fruhstuck%e2%80%9c-am-hummling-gymnasium","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2016\/07\/%e2%80%9efaires-fruhstuck%e2%80%9c-am-hummling-gymnasium\/","title":{"rendered":"\u201eFaires Fr\u00fchst\u00fcck\u201c am H\u00fcmmling-Gymnasium"},"content":{"rendered":"<p>S\u00f6gel &#8211; Reges Treiben herrschte am Dienstag, dem \u00a023. Mai 2016 ab 9 Uhr im Mensageb\u00e4ude, bis alle 260 Sch\u00fclerinnen und Sch\u00fcler mit ihren Lehrkr\u00e4ften Platz an den Tischen f\u00fcr das \u201eFaire Fr\u00fchst\u00fcck\u201c gefunden hatten. Vor ihnen auf den Tischen waren die leckersten Dinge aufgebaut, die eben zu einem Fr\u00fchst\u00fcck dazu geh\u00f6ren: Br\u00f6tchen, s\u00fc\u00dfer Aufstrich, Wurst, K\u00e4se, Kakao, S\u00e4fte und vieles mehr. Das klingt zun\u00e4chst nach einem ganz normalen Fr\u00fchst\u00fcck, sodass sich die Frage stellt: Und wo wird da der faire Handel ber\u00fccksichtigt? &#8211; Die Marmelade war aus hiesigen Erdbeeren, die die Oma gemacht hatte, die Milch stammte von K\u00fchen des Nachbarbauern; es gab frische Br\u00f6tchen, die die Mama fr\u00fch morgens noch gebacken hatte \u2013 denn die faire Handelskette beginnt nicht erst im globalen S\u00fcden! Auch der bevorzugte Konsum von hiesigen Produkten geh\u00f6rt mit zum Gedanken der Nachhaltigkeit, der durch den fairen Handel vorangetrieben werden soll.<\/p>\n<p>Andererseits konnte man auch oft das Fairtradesiegel auf den Tischen finden, das Produkte f\u00fcr ihre faire Herstellung auszeichnet. Hierunter fanden sich Honig, Marmelade und Obst, aber auch Nussnougatcreme, Schokolade und Kekse sowie viele weitere Erzeugnisse, in denen vor allem Kakao enthalten ist. Denn besonders Kakao, Kaffee und Tee z\u00e4hlen zu den Produkten, die auf bestimmte Klimabedingungen des globalen S\u00fcdens angewiesen sind. Hier sorgen verschiedene Organisationen wie die <em>Gepa<\/em>, <em>El Puente<\/em> und <em>Fairtrade Deutschland<\/em> daf\u00fcr, dass die Produzentenfamilien, die sich diesen Kooperativen angeschlossen haben, einen gerechten Lohn f\u00fcr ihre Arbeit bekommen. Dadurch haben sie ein festes Einkommen, die M\u00f6glichkeit, ihre Kinder zur Schule zu schicken und bekommen eine Pr\u00e4mie f\u00fcr ihre D\u00f6rfer, mit der beispielsweise Schulen, Brunnen und Krankenh\u00e4user finanziert werden. Daf\u00fcr lohnt es sich, beim Einkauf einmal genauer hinzuschauen und etwas mehr Geld zu investieren! Viele dieser Produkte finden sich schon in Superm\u00e4rkten und Discountern oder nat\u00fcrlich im Eine-Welt-Laden in S\u00f6gel.<\/p>\n<p>Der Direktor Herr Rojahn begr\u00fc\u00dfte alle Teilnehmerinnen und Teilnehmer herzlich zu Beginn des Fr\u00fchst\u00fccks und dann wurden die fairen Produkte mit guter Laune verzehrt. Auf dem Weg zur \u201eFair-trade-School\u201c st\u00e4rken solche Aktionen nat\u00fcrlich das Gemeinschaftsgef\u00fchl unserer Schule und sch\u00e4rfen das Bewusstsein aller Beteiligten f\u00fcr Gerechtigkeit, Globalisierung und die eigenen Handlungsm\u00f6glichkeiten in diesen Zusammenh\u00e4ngen, sodass sich der faire Gedanke immer weiter ausbreitet. Daher ist f\u00fcr die bevorstehende Festwoche zum 50-j\u00e4hrigen Jubil\u00e4um des H\u00fcmmling-Gymnasiums ein weiteres \u201eFaires Fr\u00fchst\u00fcck\u201c geplant und am letzten Schultag vor den Sommerferien werden die Siegerinnen des Schulwettbewerbs zum \u201eFair-trade- School- Logo\u201c f\u00fcr das \u201eH\u00fcm-Gym\u201c nat\u00fcrlich mit fairen Preisen geehrt.<\/p>\n<p>Text\/Foto:<strong> <\/strong>Steuergruppe Fair-trade -School des H\u00fcm-Gyms<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/07\/Faires-Fr\u00fchst\u00fcck-am-H\u00fcmmling-Gymnasium1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-19256\" title=\"Faires Fr\u00fchst\u00fcck am H\u00fcmmling-Gymnasium1\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/07\/Faires-Fr\u00fchst\u00fcck-am-H\u00fcmmling-Gymnasium1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/07\/Faires-Fr\u00fchst\u00fcck-am-H\u00fcmmling-Gymnasium2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-19257\" title=\"Faires Fr\u00fchst\u00fcck am H\u00fcmmling-Gymnasium2\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/07\/Faires-Fr\u00fchst\u00fcck-am-H\u00fcmmling-Gymnasium2-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"S\u00f6gel &#8211; Reges Treiben herrschte am Dienstag, dem \u00a023. Mai 2016 ab 9 Uhr im Mensageb\u00e4ude, bis alle 260 Sch\u00fclerinnen und Sch\u00fcler mit ihren Lehrkr\u00e4ften Platz an den Tischen f\u00fcr das \u201eFaire Fr\u00fchst\u00fcck\u201c gefunden hatten. Vor ihnen auf den Tischen waren die leckersten Dinge aufgebaut, die eben zu einem Fr\u00fchst\u00fcck dazu geh\u00f6ren: Br\u00f6tchen, s\u00fc\u00dfer Aufstrich, [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-19255","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=19255"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19255\/revisions"}],"predecessor-version":[{"id":19258,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19255\/revisions\/19258"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=19255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=19255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=19255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}