{"id":19044,"date":"2016-06-06T20:24:38","date_gmt":"2016-06-06T18:24:38","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=19044"},"modified":"2016-06-06T20:24:46","modified_gmt":"2016-06-06T18:24:46","slug":"besuch-in-der-geschichts-und-zukunftswerkstatt-in-sogel","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2016\/06\/besuch-in-der-geschichts-und-zukunftswerkstatt-in-sogel\/","title":{"rendered":"Besuch in der Geschichts- und Zukunftswerkstatt in S\u00f6gel"},"content":{"rendered":"<p align=\"left\">Spahnharrenst\u00e4tte &#8211; Die vierte Klasse fuhr am 6.04.16 mit dem Fahrrad nach S\u00f6gel und besuchte dort die Geschichts- und Zukunftswerkstatt zum Thema \u201eWald\u201c.<\/p>\n<p align=\"left\">Nach einer kurzen Einf\u00fchrung in das Thema erfuhren die Kinder an drei Stationen, wie sich der Waldbestand im Laufe der Zeit auf dem H\u00fcmmling ver\u00e4nderte, wie man neue W\u00e4lder auf dem sandigen Boden anpflanzte und wer eigentlich daf\u00fcr verantwortlich war.<\/p>\n<p align=\"left\">An einer Station wurde ein kurzes Theaterst\u00fcck dazu einge\u00fcbt, das die Kinder zum Abschluss vorf\u00fchrten.<\/p>\n<p align=\"left\">Besonders toll fanden sie, dass jeder von ihnen ein Kost\u00fcm bekam.<\/p>\n<p align=\"left\">Auf der R\u00fcckfahrt durch das Spahner S\u00fcdholz konnten sie das Geh\u00f6rte auch noch einmal sehen, n\u00e4mlich die sogenannten Rabatten, die zur Anpflanzung von B\u00e4umen angelegt wurden.<\/p>\n<p align=\"left\">Alle Kinder und auch die Begleitpersonen Frau Konen und Frau Gerdes waren sich einig, dass es ein gelungener Vormittag war, informativ und unterhaltsam.<\/p>\n<p align=\"left\">Text: Werner R\u00fcdebusch \/ Foto:\u00a0 Grundschule\/VSPH<\/p>\n<p align=\"left\"><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/06\/Besuch-in-der-Geschichts-und-Zukunftswerkstatt-in-S\u00f6gel1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-19045\" title=\"Besuch in der Geschichts- und Zukunftswerkstatt in S\u00f6gel1\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/06\/Besuch-in-der-Geschichts-und-Zukunftswerkstatt-in-S\u00f6gel1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/06\/Besuch-in-der-Geschichts-und-Zukunftswerkstatt-in-S\u00f6gel2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-19046\" title=\"Besuch in der Geschichts- und Zukunftswerkstatt in S\u00f6gel2\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/06\/Besuch-in-der-Geschichts-und-Zukunftswerkstatt-in-S\u00f6gel2-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/06\/Besuch-in-der-Geschichts-und-Zukunftswerkstatt-in-S\u00f6gel3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-19047\" title=\"Besuch in der Geschichts- und Zukunftswerkstatt in S\u00f6gel3\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2016\/06\/Besuch-in-der-Geschichts-und-Zukunftswerkstatt-in-S\u00f6gel3-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Spahnharrenst\u00e4tte &#8211; Die vierte Klasse fuhr am 6.04.16 mit dem Fahrrad nach S\u00f6gel und besuchte dort die Geschichts- und Zukunftswerkstatt zum Thema \u201eWald\u201c. Nach einer kurzen Einf\u00fchrung in das Thema erfuhren die Kinder an drei Stationen, wie sich der Waldbestand im Laufe der Zeit auf dem H\u00fcmmling ver\u00e4nderte, wie man neue W\u00e4lder auf dem sandigen [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-19044","post","type-post","status-publish","format-standard","hentry","category-aus-der-schule-geplaudert"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=19044"}],"version-history":[{"count":2,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19044\/revisions"}],"predecessor-version":[{"id":19049,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/19044\/revisions\/19049"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=19044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=19044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=19044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}