{"id":14505,"date":"2014-09-21T17:07:00","date_gmt":"2014-09-21T15:07:00","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/?p=14505"},"modified":"2014-09-21T17:07:00","modified_gmt":"2014-09-21T15:07:00","slug":"kinder-und-jugendchor-sogel-macht-fahrt-zum-internationalen-chortreffen-in-paris","status":"publish","type":"post","link":"https:\/\/www.forum-soegel.de\/information\/2014\/09\/kinder-und-jugendchor-sogel-macht-fahrt-zum-internationalen-chortreffen-in-paris\/","title":{"rendered":"Kinder- und Jugendchor S\u00f6gel macht Fahrt zum Internationalen Chortreffen in Paris"},"content":{"rendered":"<p>S\u00f6gel &#8211; Am Dienstag, dem 8.7.2014, machten wir, der Kinder- und Jugendchor S\u00f6gel, uns zusammen mit Frauke Sparfeldt (Chorleiterin) auf den Weg nach Paris. Gleich, nachdem wir ankamen, fuhren wir mit der Metro in die Stadt. Trotz des Regens liefen wir weiter, um die Sehensw\u00fcrdigkeiten u.a. den Eiffelturm, Montmartre und das dahinterliegende K\u00fcnstlerviertel \u00a0zu erkunden. Am folgenden Tag nahmen wir an einer Deutschen Messe mit Hunderten von anderen Chors\u00e4ngern\/innen in Saint \u2013Sulpice teil. Au\u00dferdem h\u00f6rten wir uns die Konzerte anderer Ch\u00f6re in Notre Dame an. Schlie\u00dflich gaben wir in der Pfarrkirche Saint\u00a0 Madeleine ein spontanes Konzert f\u00fcr die anwesenden Besucher. Am Freitag machten wir eine Stadtrundfahrt mit dem Bus, danach hatten wir Zeit, selbst zu entscheiden, was wir machten wollten. Tags darauf stand eine Besichtigung des europ\u00e4ischen Geschichtswegs, der hier erst zum Teil fertig war, auf dem Plan. (Den Geschichtsweg gibt es in S\u00f6gel \u00fcbrigens schon.) In Pontoise wurden wir sehr herzlich empfangen und bekamen\u00a0 anschlie\u00dfend ein wenig Einblick\u00a0 in die Geschichte der Stadt. Nachdem wir nach dem Besuch an van Goghs Grab ein diesmal geplantes Konzert in der Kirche von Pontoise gaben, feierten wir anschlie\u00dfend den darauf\u00a0 folgenden Gottesdienst mit. Sonntagmorgen fuhren wir mit dem Bus und dem tollen Busfahrer Peter zur\u00fcck nach S\u00f6gel, so dass wir rechtzeitig zum Finale der WM wieder da waren.<\/p>\n<p>Text: Pia Moritz<\/p>\n<p><a href=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2014\/09\/Kinder-und-Jugendchor-S\u00f6gel-machen-Fahrt-zum-Internationalen-Chortreffen-in-Paris.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14506\" title=\"Kinder und Jugendchor S\u00f6gel machen Fahrt zum Internationalen Chortreffen in Paris\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2014\/09\/Kinder-und-Jugendchor-S\u00f6gel-machen-Fahrt-zum-Internationalen-Chortreffen-in-Paris-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2014\/09\/Kinder-und-Jugendchor-S\u00f6gel-machen-Fahrt-zum-Internationalen-Chortreffen-in-Paris-300x225.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2014\/09\/Kinder-und-Jugendchor-S\u00f6gel-machen-Fahrt-zum-Internationalen-Chortreffen-in-Paris.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"S\u00f6gel &#8211; Am Dienstag, dem 8.7.2014, machten wir, der Kinder- und Jugendchor S\u00f6gel, uns zusammen mit Frauke Sparfeldt (Chorleiterin) auf den Weg nach Paris. Gleich, nachdem wir ankamen, fuhren wir mit der Metro in die Stadt. Trotz des Regens liefen wir weiter, um die Sehensw\u00fcrdigkeiten u.a. den Eiffelturm, Montmartre und das dahinterliegende K\u00fcnstlerviertel \u00a0zu erkunden. [&hellip;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[276],"tags":[],"class_list":["post-14505","post","type-post","status-publish","format-standard","hentry","category-jugend-schreibt"],"_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/14505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=14505"}],"version-history":[{"count":1,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/14505\/revisions"}],"predecessor-version":[{"id":14507,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/14505\/revisions\/14507"}],"wp:attachment":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media?parent=14505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/categories?post=14505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/tags?post=14505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}