{"id":25391,"date":"2018-12-02T12:32:46","date_gmt":"2018-12-02T11:32:46","guid":{"rendered":"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/12\/Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2.jpg"},"modified":"2018-12-02T12:32:46","modified_gmt":"2018-12-02T11:32:46","slug":"klasse-3-der-grundschule-st-johannes-besichtigt-kreutzmanns-muehle-in-werlte-2","status":"inherit","type":"attachment","link":"https:\/\/www.forum-soegel.de\/information\/2018\/11\/klasse-3-der-grundschule-st-johannes-besichtigt-kreutzmanns-muehle-in-werlte\/klasse-3-der-grundschule-st-johannes-besichtigt-kreutzmanns-muehle-in-werlte-2\/","title":{"rendered":"Klasse 3 der Grundschule St. Johannes besichtigt Kreutzmanns M\u00fchle in Werlte (2)"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-25391","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/12\/Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/12\/Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/12\/Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2-300x225.jpg 300w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/12\/Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2-768x576.jpg 768w, https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/12\/Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":768,"file":"2018\/12\/Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2.jpg","sizes":{"thumbnail":{"file":"Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/12\/Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2-150x150.jpg"},"medium":{"file":"Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/12\/Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2-300x225.jpg"},"medium_large":{"file":"Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/12\/Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2-768x576.jpg"},"large":{"file":"Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/12\/Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2-1024x768.jpg"},"full":{"file":"Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/12\/Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":25388,"source_url":"https:\/\/www.forum-soegel.de\/information\/wp-content\/uploads\/2018\/12\/Klasse-3-der-Grundschule-St.-Johannes-besichtigt-Kreutzmanns-M\u00fchle-in-Werlte-2.jpg","_links":{"self":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media\/25391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/comments?post=25391"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":25388,"href":"https:\/\/www.forum-soegel.de\/information\/wp-json\/wp\/v2\/posts\/25388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}